{"id":1541,"date":"2022-01-25T12:47:20","date_gmt":"2022-01-25T11:47:20","guid":{"rendered":"https:\/\/chaxigallery.com\/?page_id=1541"},"modified":"2022-02-06T08:21:31","modified_gmt":"2022-02-06T07:21:31","slug":"policy-asta","status":"publish","type":"page","link":"https:\/\/chaxigallery.com\/it_it\/policy-asta\/","title":{"rendered":"Policy Asta"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1541\" class=\"elementor elementor-1541\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-79682ee5 elementor-section-stretched elementor-section-full_width elementor-section-height-min-height elementor-section-items-bottom elementor-section-height-default elementor-invisible\" data-id=\"79682ee5\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_delay&quot;:400,&quot;shape_divider_bottom&quot;:&quot;opacity-tilt&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 2600 131.1\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M0 0L2600 0 2600 69.1 0 0z\"\/>\n\t<path class=\"elementor-shape-fill\" style=\"opacity:0.5\" d=\"M0 0L2600 0 2600 69.1 0 69.1z\"\/>\n\t<path class=\"elementor-shape-fill\" style=\"opacity:0.25\" d=\"M2600 0L0 0 0 130.1 2600 69.1z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5eb8ef82\" data-id=\"5eb8ef82\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1f075335 elementor-shape-circle e-grid-align-left elementor-absolute elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"1f075335\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-repeater-item-57f2213\" href=\"https:\/\/www.facebook.com\/Chaxi-Gallery-104705405024715\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-facebook\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256C504 119 393 8 256 8S8 119 8 256c0 123.78 90.69 226.38 209.25 245V327.69h-63V256h63v-54.64c0-62.15 37-96.48 93.67-96.48 27.14 0 55.52 4.84 55.52 4.84v61h-31.28c-30.8 0-40.41 19.12-40.41 38.73V256h68.78l-11 71.69h-57.78V501C413.31 482.38 504 379.78 504 256z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-7b1709b\" href=\"https:\/\/www.instagram.com\/chaxi_gallery\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-instagram\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.1 141c-63.6 0-114.9 51.3-114.9 114.9s51.3 114.9 114.9 114.9S339 319.5 339 255.9 287.7 141 224.1 141zm0 189.6c-41.1 0-74.7-33.5-74.7-74.7s33.5-74.7 74.7-74.7 74.7 33.5 74.7 74.7-33.6 74.7-74.7 74.7zm146.4-194.3c0 14.9-12 26.8-26.8 26.8-14.9 0-26.8-12-26.8-26.8s12-26.8 26.8-26.8 26.8 12 26.8 26.8zm76.1 27.2c-1.7-35.9-9.9-67.7-36.2-93.9-26.2-26.2-58-34.4-93.9-36.2-37-2.1-147.9-2.1-184.9 0-35.8 1.7-67.6 9.9-93.9 36.1s-34.4 58-36.2 93.9c-2.1 37-2.1 147.9 0 184.9 1.7 35.9 9.9 67.7 36.2 93.9s58 34.4 93.9 36.2c37 2.1 147.9 2.1 184.9 0 35.9-1.7 67.7-9.9 93.9-36.2 26.2-26.2 34.4-58 36.2-93.9 2.1-37 2.1-147.8 0-184.8zM398.8 388c-7.8 19.6-22.9 34.7-42.6 42.6-29.5 11.7-99.5 9-132.1 9s-102.7 2.6-132.1-9c-19.6-7.8-34.7-22.9-42.6-42.6-11.7-29.5-9-99.5-9-132.1s-2.6-102.7 9-132.1c7.8-19.6 22.9-34.7 42.6-42.6 29.5-11.7 99.5-9 132.1-9s102.7-2.6 132.1 9c19.6 7.8 34.7 22.9 42.6 42.6 11.7 29.5 9 99.5 9 132.1s2.7 102.7-9 132.1z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-twitch elementor-repeater-item-a17d664\" href=\"https:\/\/www.twitch.tv\/chaxigallery\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Twitch<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-twitch\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M391.17,103.47H352.54v109.7h38.63ZM285,103H246.37V212.75H285ZM120.83,0,24.31,91.42V420.58H140.14V512l96.53-91.42h77.25L487.69,256V0ZM449.07,237.75l-77.22,73.12H294.61l-67.6,64v-64H140.14V36.58H449.07Z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-youtube elementor-repeater-item-126645c\" href=\"https:\/\/www.youtube.com\/channel\/UCLHvtPakMQJmU3867sJEB-g\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Youtube<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-youtube\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M549.655 124.083c-6.281-23.65-24.787-42.276-48.284-48.597C458.781 64 288 64 288 64S117.22 64 74.629 75.486c-23.497 6.322-42.003 24.947-48.284 48.597-11.412 42.867-11.412 132.305-11.412 132.305s0 89.438 11.412 132.305c6.281 23.65 24.787 41.5 48.284 47.821C117.22 448 288 448 288 448s170.78 0 213.371-11.486c23.497-6.321 42.003-24.171 48.284-47.821 11.412-42.867 11.412-132.305 11.412-132.305s0-89.438-11.412-132.305zm-317.51 213.508V175.185l142.739 81.205-142.739 81.201z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6f21e1dd elementor-widget elementor-widget-image\" data-id=\"6f21e1dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"462\" src=\"https:\/\/chaxigallery.com\/wp-content\/uploads\/2021\/03\/Logo-grigio-trasoa-768x462.png\" class=\"attachment-medium_large size-medium_large wp-image-50\" alt=\"\" srcset=\"https:\/\/chaxigallery.com\/wp-content\/uploads\/2021\/03\/Logo-grigio-trasoa-768x462.png 768w, https:\/\/chaxigallery.com\/wp-content\/uploads\/2021\/03\/Logo-grigio-trasoa-600x361.png 600w, https:\/\/chaxigallery.com\/wp-content\/uploads\/2021\/03\/Logo-grigio-trasoa-300x180.png 300w, https:\/\/chaxigallery.com\/wp-content\/uploads\/2021\/03\/Logo-grigio-trasoa-1024x616.png 1024w, https:\/\/chaxigallery.com\/wp-content\/uploads\/2021\/03\/Logo-grigio-trasoa-1536x924.png 1536w, https:\/\/chaxigallery.com\/wp-content\/uploads\/2021\/03\/Logo-grigio-trasoa-2048x1232.png 2048w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-39a13430 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"39a13430\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-30a5acf9\" data-id=\"30a5acf9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-eb8a022 elementor-widget elementor-widget-text-editor\" data-id=\"eb8a022\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ol><li><strong> DEFINI<\/strong><strong>ZIONI<\/strong><\/li><\/ol><p><strong>Definizioni Acquirente<\/strong>: la persona fisica o giuridica che in relazione al lotto fa, in asta, l\u2019offerta pi\u00f9 alta accettata dal banditore; Codice del Consumo: il Decreto Legislativo del 6 settembre 2005, n. 2016; Codice Urbani: il Decreto Legislativo del 22 gennaio 2004, n. 42 e sue successive modificazioni o integrazioni.<\/p><p><strong>Commissione di acquisto<\/strong>: il compenso dovuto a CHAXI dall\u2019Acquirente in relazione all\u2019acquisto del lotto e calcolato in misura percentuale al Prezzo, in base al valore percentuale indicato nel catalogo d\u2019asta ovvero nelle presenti Condizioni Generali di Vendita, oltre a qualsiasi importo dovuto a CHAXI dall\u2019Acquirente a titolo di IVA o di importo in sostituzione di IVA;<\/p><p><strong>Condizioni Generali di Mandato<\/strong>: le condizioni generali di mandato applicate al Venditore;<\/p><p><strong>Condizioni Generali di Vendita<\/strong>: le presenti condizioni generali di vendita;<\/p><p><strong>Contraffazione<\/strong>: secondo la ragionevole opinione di CHAXI, l\u2019imitazione di un lotto offerto in vendita, non descritta come tale nel catalogo d\u2019asta, creata a scopo di inganno su paternit\u00e0, autenticit\u00e0, provenienza, attribuzione, origine, fonte, data, et\u00e0, periodo, che alla data della vendita aveva un valore inferiore a quello che avrebbe avuto se il lotto fosse stato corrispondente alla descrizione del catalogo d\u2019asta. Non costituisce una contraffazione un lotto che sia stato restaurato o sottoposto ad opera di modifica di qualsiasi natura (tra cui la ripitturazione o la sovrapitturazione);<\/p><p>CHAXI: CHAXI GALLERY di Imane Chakhsi, con sede legale a Roncadelle (BS), Via Pietro Cismondi n. 15, C.F., P. IVA e numero di iscrizione al Registro Imprese di Brescia 03977760986, BS \u2013 578998;<\/p><p><strong>Importo totale dovuto<\/strong>: il Prezzo, oltre alla Commissione di acquisto e alle Spese;<\/p><p><strong>Mandato<\/strong>: il contratto di mandato con rappresentanza stipulato, di volta in volta, tra CHAXI e il Venditore, cui saranno applicabili le Condizioni Generali di Mandato;<\/p><p><strong>Prezzo<\/strong>: il prezzo a cui il lotto viene aggiudicato in asta dal banditore all\u2019Acquirente, al netto della Commissione di acquisto;<\/p><p><strong>Riserva<\/strong>: il prezzo minimo confidenziale a cui il Venditore ha concordato con CHAXI di vendere il Lotto o, in mancanza di accordo tra CHAXI e il Venditore, un importo pari al settantacinque per cento (75%) della Stima minima di prevendita;<\/p><p><strong>Sito<\/strong>: www.chaxigallery.com;<\/p><p><strong>Spese<\/strong>: in relazione all\u2019acquisto di un lotto, sono tutte le spese dovute dall\u2019Acquirente a CHAXI e comprendono (ma non si limitano a): le imposte di qualsiasi tipo, i costi di imballaggio e di spedizione, le spese di recupero delle somme dovute dall\u2019Acquirente inadempiente, le eventuali spese di riproduzione del lotto ovvero di sua perizia e\/o autentica, il diritto di seguito, che l\u2019Acquirente si impegna a pagare e che spetterebbe al Venditore pagare in base all\u2019art. 152, comma 1, Legge 22 aprile 1941, n. 633;<\/p><p><strong>Stima minima prevendita<\/strong>: la stima minima finale alla quale viene offerto in vendita il lotto, comunicata o meno al Venditore.<\/p><p><strong>Venditore<\/strong>: la persona fisica o giuridica che conferisce a CHAXI, in qualit\u00e0 di mandataria con rappresentanza, il diritto esclusivo di offrire in vendita in asta il lotto. Nel caso sia offerto in vendita un bene in compropriet\u00e0, Venditore sar\u00e0 considerato ciascuno dei comproprietari il quale assumer\u00e0 solidalmente nei confronti di CHAXI tutti gli obblighi derivanti dal Mandato.<\/p><p><strong>\u00a0<\/strong><\/p><ol start=\"2\"><li><strong> INFORMAZIONI IMPORTANTI PER GLI ACQUIRENTI<\/strong><\/li><\/ol><ul><li><strong>1 Comprare all\u2019Asta.<\/strong><\/li><\/ul><p>CHAXI agisce in nome e per conto del Venditore, in qualit\u00e0 di mandataria con rappresentanza dello stesso e dunque come mera intermediaria tra Acquirente e Venditore. Pertanto la vendita del lotto deve considerarsi avvenuta tra Acquirente e Venditore. I potenziali Acquirenti sono tenuti a consultare il Sito per prendere visione della catalogazione pi\u00f9 aggiornata dei lotti presenti in catalogo.<\/p><ul><li><strong>2 Provenienza.<\/strong><\/li><\/ul><p>In alcune circostanze, CHAXI pu\u00f2 stampare sul catalogo d\u2019asta la storia della propriet\u00e0 di un lotto quando ritiene che quell\u2019informazione possa contribuire al suo studio o se aiuta a distinguere il lotto medesimo. Tuttavia, l\u2019identit\u00e0 del Venditore o dei precedenti proprietari potr\u00e0 non essere resa pubblica per una serie di ragioni, per esempio per rispettare la richiesta di riservatezza da parte del Venditore o perch\u00e9 l\u2019identit\u00e0 del precedente proprietario non \u00e8 nota a causa dell\u2019et\u00e0 del lotto.<\/p><ul><li><strong>3 Prezzo e Commissione di acquisto e IVA.<\/strong><\/li><\/ul><p>Al Prezzo del lotto sar\u00e0 aggiunta una Commissione di acquisto che l\u2019Acquirente \u00e8 tenuto a pagare quale parte dell\u2019Importo totale dovuto.<\/p><p>La Commissione di acquisto \u00e8 stabilita nella misura del:<\/p><p>24% (19,68 + IVA) del Prezzo del lotto fino alla concorrenza dell\u2019importo di euro 2.999,99;<\/p><p>22% (18,04 + IVA) per ogni parte del Prezzo eccedente l\u2019importo di euro 2.999,99 fino alla<\/p><p>\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0concorrenza dell\u2019importo di euro 9.999,99;<\/p><p>20% (16,40 + IVA) per ogni parte del Prezzo eccedente l\u2019importo di euro 9.999,99 fino alla<\/p><p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 concorrenza dell\u2019importo di euro 59.999,99;<\/p><p>19% (14,82 + IVA) per ogni parte del Prezzo eccedente l\u2019importo di euro 59.999,99 fino alla<\/p><p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 concorrenza dell\u2019importo di euro 99.999,99;<\/p><p>18% (14,04 + IVA) per ogni parte del Prezzo eccedente l\u2019importo di euro 99.999,99 fino alla<\/p><p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 concorrenza dell\u2019importo di euro 299.999,99;<\/p><p>15% (12,30 + IVA) per ogni parte del Prezzo eccedente l\u2019importo di euro 299.999,99.<\/p><p>Per le aste dei dipartimenti di Vini e Distillati e di Fumetti la Commissione di acquisto \u00e8 stabilita nella misura fissa del 20% (16,40 + IVA).<\/p><p>Per le aste del dipartimento di Orologi la commissioni di acquisto \u00e8 stabilita nella misura del:<\/p><p>22% (18,03 + IVA) del Prezzo del lotto fino alla concorrenza dell\u2019importo di euro 99.999,99<\/p><p>20% (16,40 + IVA) per ogni parte del Prezzo eccedente l\u2019importo di euro 99.999,99<\/p><p>Per le aste del dipartimento di Automotive la commissione di acquisto \u00e8 stabilita nella misura del:<\/p><p>16,47% (13,5 + IVA) del Prezzo del lotto fino alla concorrenza dell\u2019importo di euro 499.999,99;<\/p><p>13,42% (11 + IVA) per ogni parte del Prezzo eccedente l\u2019importo di euro 499.999,99.<\/p><p>Nel caso in cui, con riferimento ad uno specifico lotto, le percentuali indicate nel catalogo d\u2019asta fossero diverse da quelle qui specificate, prevarranno le percentuali indicate nel catalogo.<\/p><ul><li><strong>4 IVA<\/strong><\/li><\/ul><p>Un\u2019Imposta sul Valore Aggiunto (IVA) pu\u00f2 essere applicata sul Prezzo e\/o sulla Commissione di acquisto. Si prega di fare riferimento alle informazioni relative all\u2019IVA, contenute nella sezione \u201cSimboli\u201d, che segue.<\/p><p>Al fine di armonizzare le procedure fiscali tra i Paesi dell\u2019Unione Europea, con decorrenza dal 1\u00b0 gennaio 2001 sono state introdotte in Italia nuove regole con l\u2019estensione alle Case d\u2019Asta del regime del margine. L\u2019art. 45 della legge 342 del 21 Novembre 2000 prevede l\u2019applicazione di tale regime alle vendite concluse in esecuzione ai contratti di commissione definiti con: (a) soggetti privati; (b) soggetti passivi d\u2019imposta che hanno assoggettato l\u2019operazione al regime del margine; (c) soggetti che non hanno potuto detrarre l\u2019imposta ai sensi degli art. 19, 19-bis, e 19-bis2 del DPR. 633\/72 (che hanno venduto il lotto in esenzione ex art. 10, 27-quinquies); (d) soggetti che beneficiano del regime di franchigia previsto per le piccole imprese nello Stato di appartenenza. In forza della speciale normativa, nei casi sopracitati eventuale imposta IVA, ovvero una somma sostitutiva di IVA, se applicabile, viene applicata da CHAXI. Nessun particolare simbolo verr\u00e0 usato per identificare i lotti venduti nel regime del margine.<\/p><p><strong>\u00a0<\/strong><\/p><ul><li><strong>5 Diritto di seguito.<\/strong><\/li><\/ul><p>Oltre al Prezzo, alla Commissione di acquisto e alle altre Spese, l\u2019Acquirente si impegna a pagare a CHAXI, qualora dovuto, il \u201cdiritto di seguito\u201d ex artt. 144 e ss. della Legge 22 aprile 1941, n. 633 e successive modificazioni e integrazioni che spetterebbe al Venditore pagare in base all\u2019art. 152, comma 1, Legge 22 aprile 1941, n. 633 e successive modificazioni e integrazioni. Il \u201cdiritto di seguito\u201d sar\u00e0 corrisposto dall\u2019Acquirente in accordo con l\u2019art. 7 e sar\u00e0 versato alla (S.I.A.E.) da CHAXI. I lotti soggetti a diritto di seguito sono contrassegnati con il simbolo (\u00ae) nella percentuale sotto indicata per un importo totale comunque non superiore a euro 12.500,00. Il \u201cdiritto di seguito\u201d \u00e8 dovuto solo se il prezzo della vendita non \u00e8 inferiore a euro 3.000,00. Esso \u00e8 cos\u00ec determinato:<\/p><p>4% per la parte del prezzo di vendita compresa tra euro 0 e euro 50.000,00;<\/p><p>3% per la parte del prezzo di vendita compresa tra euro 50.000,01 e euro 200.000,00;<\/p><p>1% per la parte del prezzo di vendita compresa tra euro 200.000,01 e euro 350.000,00;<\/p><p>0,5% per la parte del prezzo di vendita com\u00adpresa tra euro 350.000,01 e euro 500.000,00;<\/p><p>0,25% per la parte del prezzo di vendita superi\u00adore a euro 500.000,00.<\/p><ul><li><strong>6 Valute<\/strong><\/li><\/ul><p>Durante alcune aste potr\u00e0 essere operante uno schermo che indica i cambi aggiornati delle principali valute estere, in contemporanea con le offerte effettuate in sala d\u2019asta. I cambi sono da considerarsi solo indicativi e tutte le offerte in sala saranno espresse in Euro. CHAXI declina ogni responsabilit\u00e0 per ogni errore ed omissione che apparir\u00e0 su detto schermo. Il pagamento dei lotti acquistati dovr\u00e0 essere in Euro. L\u2019ammontare equivalente potr\u00e0 essere effettuato in valuta estera purch\u00e9 in base al cambio del giorno in cui il pagamento verr\u00e0 effettuato.<\/p><ul><li><strong>7 Sicurezza<\/strong><\/li><\/ul><p>Per salvaguardare la sicurezza dei potenziali Acquirenti e degli Acquirenti durante la permanenza nei nostri spazi espositivi, CHAXI espone tutte le opere in modo tale da non creare eventuali pericoli. Tuttavia, nel caso in cui un potenziale Acquirente maneggiasse lotti in esposizione, ci\u00f2 \u00e8 a suo esclusivo rischio e pericolo. Alcuni lotti di grandi dimensioni e pesanti possono essere pericolosi se maneggiati in modo errato. Nel caso in cui si desiderasse ispezionare accuratamente un lotto, La preghiamo di richiedere l\u2019assistenza del personale di CHAXI. Alcuni lotti in esposizione potrebbero essere segnalati con la dicitura \u201cper cortesia non toccare\u201d ovvero con altra dicitura simile. Nel caso in cui si intenda esaminare questi lotti, si prega di richiedere l\u2019assistenza del personale CHAXI. In ogni caso, salvo dolo o colpa grave, CHAXI non sar\u00e0 in alcun modo responsabile per eventuali danni subiti dal potenziale Acquirente, dall\u2019Acquirente ovvero da un suo studioso o da un suo esperto indipendente in occasione dell\u2019ispezione del lotto.<\/p><p><strong>\u00a0<\/strong><\/p><ol start=\"3\"><li><strong> PRIMA DELL\u2019ASTA<\/strong><\/li><\/ol><ul><li><strong>1 Stime pubblicate in catalogo<\/strong><\/li><\/ul><p>Le stime pubblicate in catalogo sono solo indicative per i potenziali acquirenti e sono soggette a revisione. Il Prezzo potr\u00e0 essere superiore o inferiore alle valutazioni indicate. Resta inteso che stime indicate in catalogo d\u2019asta non comprendono la Commissione di acquisto e l\u2019IVA. I potenziali Acquirenti sono tenuti a consultare il Sito per prendere visione della catalogazione pi\u00f9 aggiornata dei lotti presenti in catalogo.<\/p><ul><li><strong>2 Simboli<\/strong><\/li><\/ul><p>Il catalogo d\u2019asta potr\u00e0 contenere i seguenti simboli:<\/p><ul><li><strong>0: Importo minimo garantito<\/strong><\/li><\/ul><p>Nel caso in cui un lotto sia contrassegnato da questo simbolo al Venditore \u00e8 stato garantito un importo minimo nell\u2019ambito di una o pi\u00f9 aste.<\/p><ul><li><strong>\u03a1: Lotti di propriet\u00e0 di CHAXI<\/strong>.<\/li><\/ul><p>Nel caso in cui i lotti siano contrassegnati da questo simbolo la propriet\u00e0 appartiene in tutto o in parte a CHAXI.<\/p><ul><li><strong>PI: Parte Interessata.<\/strong><\/li><\/ul><p>Indica il caso in cui possano essere effettuate offerte sul lotto anche da parte di soggetti aventi un interesse diretto o indiretto sul medesimo, quale ad esempio il beneficiario o l\u2019esecutore testamentario che abbia venduto il lotto oppure il comproprietario del lotto o un soggetto che abbia prestato una garanzia per il lotto.<\/p><ul><li><strong>SR Senza Riserva.<\/strong><\/li><\/ul><p>I lotti illustrati nel catalogo che non sono contrassegnati da questo simbolo (SR), si intendono soggetti alla vendita con riserva. Generalmente la Riserva corrisponde ad una percentuale della Stima minima prevendita e non supera tale valore. Nel caso in cui un lotto sia venduto senza Riserva, verr\u00e0 contrassegnato da questo simbolo.<\/p><p><strong>*\u00a0 Diritto di Seguito.<\/strong><\/p><p>Per i lotti contrassegnati da questo simbolo, l\u2019Acquirente si impegna a pagare il \u201cdiritto di seguito\u201d, che spetterebbe al venditore pagare in base all\u2019art. 152, comma 1, Legge 22 aprile 1941, n. 633 e successive modificazioni e integrazioni, nella misura determinata nella sezione \u201cDiritto di seguito\u201d di cui sopra.<\/p><p><strong>\u00a0<\/strong><\/p><ul><li><strong>I: Lotto proveniente da impresa.<\/strong><\/li><\/ul><p>Per i lotti contrassegnati da questo simbolo il Prezzo \u00e8 soggetto ad IVA.<\/p><p>TI Lotto in regime di temporanea importazione.<\/p><p>Lotto in regime di temporanea importazione ex art. 72 del Codice Urbani o per il quale \u00e8 stata richiesta la temporanea importazione.<\/p><p>ID Lotto in temporanea importazione doganale.<\/p><p>I lotti contrassegnati da questo simbolo sono soggetti ad IVA (attualmente pari ad una percentuale del 10%) sul Prezzo e sul diritto di seguito, dove applicabile per i residenti in Italia. Qualsiasi costo connesso alla chiusura della temporanea importazione doganale \u00e8 a carico dell\u2019Acquirente.<\/p><p>IA Lotto in temporanea importazione artistica.<\/p><ol start=\"4\"><li><strong> L\u2019asta<\/strong><\/li><\/ol><p><strong>4.1 Svolgimento dell\u2019asta<\/strong><\/p><ul><li><strong>1.1 <\/strong>L\u2019asta \u00e8 regolata dalle Condizioni Generali di Vendita e dalle Condizioni Generali di Mandato. Le Condizioni Generali di Vendita possono essere modificate mediante un avviso affisso nella sala d\u2019asta o tramite un annuncio fatto dal banditore d\u2019asta prima dell\u2019inizio dell\u2019asta. Nell\u2019ipotesi in cui CHAXI permetta la partecipazione all\u2019asta anche online queste modifiche sono portate a conoscenza anche tramite il Sito prima dell\u2019inizio dell\u2019asta.<\/li><\/ul><ul><li><strong>1.2<\/strong> Le offerte possono essere eseguite personalmente mediante una paletta durante l\u2019asta, mediante un\u2019offerta scritta prima dell\u2019asta, per telefono ovvero via internet (in quest\u2019ultimo caso solo se possibile in relazione alla specifica asta).<\/li><\/ul><ul><li><strong>1.3<\/strong> Nell\u2019ipotesi in cui il Venditore sia un professionista e l\u2019Acquirente sia un consumatore ai sensi dell\u2019art. 3 del Codice del Consumo, le vendite concluse mediante offerte scritte, telefoniche o offerte online costituiscono contratti a distanza ai sensi e per gli effetti degli artt. 45 e ss. del Codice del Consumo.<\/li><\/ul><ul><li><strong>1.4<\/strong> La velocit\u00e0 dell\u2019asta pu\u00f2 variare.<\/li><\/ul><ul><li><strong>1.5<\/strong> L\u2019incremento delle offerte \u00e8 generalmente del dieci per cento (10%) rispetto a quella precedente.<\/li><\/ul><ul><li><strong>1.6<\/strong> A sua completa discrezione, CHAXI ha il diritto di rifiutare a chiunque di partecipare alle aste.<\/li><\/ul><ul><li><strong>1.7<\/strong> Nei confronti di ciascun potenziale Acquirente, CHAXI si riserva la facolt\u00e0 di subordinare la partecipazione all\u2019asta all\u2019esibizione di una lettera di referenze bancarie oppure al deposito di una somma a garanzia dell\u2019esatto adempimento delle obbligazioni previste dalle presenti Condizioni Generali di Vendita che sar\u00e0 restituita una volta conclusa l\u2019asta.<\/li><\/ul><ul><li><strong>1.8<\/strong> Chiunque faccia un\u2019offerta ad un\u2019asta sar\u00e0 considerato parte direttamente interessata all\u2019acquisto, salvo accordo scritto fra il partecipante all\u2019asta e CHAXI in base al quale il partecipante dichiara di agire in nome e per conto di un terzo che sia da CHAXI accettato.<\/li><\/ul><ul><li><strong>1.9<\/strong> Nel caso in cui una persona a cui sia stata concessa la possibilit\u00e0 di effettuare un\u2019offerta relativa ad un lotto abbia un interesse diretto o indiretto sul medesimo, quale ad esempio il beneficiario o l\u2019esecutore testamentario che abbia venduto il lotto, oppure il comproprietario del lotto o un\u2019altra parte che abbia prestato una garanzia per il lotto, CHAXI ne dar\u00e0 comunicazione in catalogo.<\/li><\/ul><ul><li><strong>1.10<\/strong> Il banditore conduce l\u2019asta partendo dall\u2019offerta che considera adeguata, in funzione del valore del lotto e delle offerte concorrenti. Il banditore pu\u00f2 aprire le offerte su ogni lotto formulando un\u2019offerta nell\u2019interesse del Venditore. Il banditore pu\u00f2 inoltre fare offerte nell\u2019interesse del Venditore, fino all\u2019ammontare della Riserva, formulando offerte consecutive o in risposta ad altre offerte.<\/li><li><strong>1.11<\/strong> Il colpo di martello del banditore determina l\u2019accettazione dell\u2019offerta pi\u00f9 alta, del Prezzo e, conseguentemente, la conclusione del contratto di vendita tra il Venditore e l\u2019Acquirente.<\/li><\/ul><ul><li><strong>1.12<\/strong> l banditore pu\u00f2, a sua assoluta discrezione e in un momento qualsiasi dell\u2019asta:<\/li><li>ritirare un lotto dall\u2019asta;<\/li><li>riformulare un\u2019offerta di vendita per un lotto, qualora abbia motivi per ritenere che ci sia un errore<\/li><li>una disputa; e\/o<\/li><li>adottare qualsiasi provvedimento che ritenga adatto alle circostanze, come abbinare o separare i lotti o cambiarne l\u2019ordine di vendita purch\u00e9 il lotto non sia offerto in asta una giornata anteriore;<\/li><li>rispetto a quella indicata nel catalogo d\u2019asta.<\/li><\/ul><ul><li><strong>1.13<\/strong> Durante alcune aste potr\u00e0 essere operante uno schermo video. CHAXI declina ogni responsabilit\u00e0 sia in relazione alla corrispondenza dell\u2019immagine sullo schermo all\u2019originale, sia per errori nel funzionamento dello schermo video.<\/li><\/ul><ul><li><strong>1.14<\/strong> CHAXI dichiara che il lotto pu\u00f2 essere oggetto di dichiarazione di interesse culturale da parte del Ministero dei beni e delle attivit\u00e0 culturali e del turismo ai sensi dell\u2019art. 13 del Codice Urbani. In tal caso o nel caso in cui in relazione al lotto sia stato avviato il procedimento di dichiarazione di interesse culturale ai sensi dell\u2019art. 14 del Codice Urbani, CHAXI ne dar\u00e0 comunicazione prima della vendita. Nel caso in cui il lotto sia stato oggetto di dichiarazione di interesse culturale il Venditore provveder\u00e0 a denunciare la vendita al Ministero competente ex art. 59 Codice Urbani. La vendita sar\u00e0 sospensivamente condizionata al mancato esercizio da parte del Ministero competente del diritto di prelazione nel termine di sessanta (60) giorni dalla data di ricezione della denuncia, ovvero nel termine maggiore di centottanta (180) giorni di cui all\u2019art. 61, comma 2, del Codice Urbani. In pendenza del termine per l\u2019esercizio della prelazione il lotto non potr\u00e0 essere consegnato all\u2019 Acquirente in base a quanto stabilito dall\u2019art. 61 del Codice Urbani.<\/li><\/ul><ul><li><strong>1.15<\/strong> Generalmente la Riserva non supera la Stima minima pre-vendita annunciata o pubblicata da CHAXI, salvo nel caso in cui la Riserva sia espressa in una moneta diversa dall\u2019euro e vi siano sensibili fluttuazioni del tasso di cambio fra la data in cui \u00e8 stata pattuita la Riserva e la data dell\u2019asta. In tal caso, salvo diverso accordo fra CHAXI ed il Venditore, la Riserva sar\u00e0 modificata in un importo pari all\u2019equivalente in euro in base al tasso ufficiale di cambio del giorno immediatamente precedente quello dell\u2019asta.<\/li><\/ul><ul><li><strong>1.16<\/strong> Offerte \u201cal meglio\u201d, \u201csalvo visione\u201d o che comprendono lotti in alternativa a quello indicato non sono accettate.<\/li><\/ul><p><strong>4.2 Offerte in sala<\/strong><\/p><ul><li><strong>2.1<\/strong> Per partecipare all\u2019asta in sala tutti i potenziali Acquirenti dovranno munirsi \u2013 prima che inizi l\u2019asta \u2013 di una paletta numerata per esprimere le proprie offerte.<\/li><\/ul><ul><li><strong>2.2<\/strong> La paletta numerata verr\u00e0 consegnata al potenziale Acquirente dal personale di CHAXI al banco registrazione a seguito dell\u2019esibizione di un documento di identit\u00e0, della compilazione e della firma dell\u2019apposito modulo di registrazione e attribuzione della paletta numerata.<\/li><\/ul><ul><li><strong>2.3<\/strong> Compilando e firmando il modulo di registrazione e attribuzione della paletta numerata, ciascun potenziale Acquirente accetta le Condizioni Generali di Vendita incluse nel catalogo.<\/li><\/ul><ul><li><strong>2.4<\/strong> \u00c8 possibile registrarsi all\u2019asta anche durante i giorni dell\u2019esposizione che precede l\u2019asta.<\/li><\/ul><ul><li><strong>2.5<\/strong> \u00c8 possibile partecipare all\u2019asta in nome e per conto di un\u2019altra persona fisica o giuridica. In tal caso, in occasione della registrazione all\u2019asta, dovr\u00e0 essere esibita idonea procura scritta rilasciata dal rappresentato con allegato un documento di identit\u00e0 del rappresentato. Il partecipante all\u2019asta sar\u00e0 solidalmente obbligato con il terzo interessato nei confronti di CHAXI in relazione a tutti gli obblighi derivanti dalle presenti Condizioni Generali di Vendita. Nel caso in cui il rappresentato sia una persona giuridica, la procura dovr\u00e0 essere sottoscritta dal legale rappresentante o da un procuratore dotato di potere di firma la cui carta di identit\u00e0 dovr\u00e0 essere allegata alla procura. CHAXI si riserva la facolt\u00e0 di non fare partecipare all\u2019asta il rappresentante qualora, a suo insindacabile giudizio, non ritenga dimostrato il potere di rappresentanza.<\/li><\/ul><ul><li><strong>2.6<\/strong> Le palette numerate devono essere utilizzate per indicare le offerte al banditore durante l\u2019asta.<\/li><\/ul><ul><li><strong>2.7<\/strong> In caso di aggiudicazione di un lotto, si prega di accertarsi che la paletta possa essere vista dal banditore e che sia il numero ivi indicato ad essere stato annunciato.<\/li><\/ul><ul><li><strong>2.8<\/strong> Nell\u2019ipotesi di dubbi riguardo al Prezzo o all\u2019Acquirente, siete pregati di attirare immediatamente l\u2019attenzione del banditore.<\/li><\/ul><ul><li><strong>2.9<\/strong> Tutti i lotti venduti saranno fatturati al nome ed all\u2019indirizzo rilasciati al momento dell\u2019assegnazione della paletta numerata e non potranno essere trasferiti ad altri nomi e indirizzi.<\/li><\/ul><ul><li><strong>2.10<\/strong> L\u2019eventuale perdita della paletta dovr\u00e0 essere immediatamente comunicata all\u2019assistente del banditore che provveder\u00e0 a fornire al potenziale Acquirente una nuova paletta.<\/li><\/ul><ul><li><strong>2.11<\/strong> Al termine dell\u2019asta la paletta deve essere restituita al banco registrazioni.<\/li><\/ul><p><strong>4.3 Offerte scritte<\/strong><\/p><ul><li><strong>3.1<\/strong> Mediante la compilazione e l\u2019invio dell\u2019apposito modulo di offerta (insieme alla documentazione in esso richiesta) allegato al catalogo d\u2019asta e caricato sul Sito \u00e8 possibile formulare offerte scritte.<\/li><\/ul><ul><li><strong>3.2<\/strong> CHAXI dar\u00e0 esecuzione alle offerte per conto del potenziale Acquirente.<\/li><\/ul><ul><li><strong>3.3<\/strong> Il servizio \u00e8 gratuito e confidenziale.<\/li><\/ul><ul><li><strong>3.4<\/strong> Il modulo di offerta dovr\u00e0 essere inviato a CHAXI almeno ventiquattro (24) ore prima dell\u2019asta.<\/li><\/ul><ul><li><strong>3.5<\/strong> Le offerte scritte saranno accettate da CHAXI soltanto se sufficientemente chiare e complete,<\/li><\/ul><p>con particolare riferimento al lotto e al prezzo a cui si intende aggiudicare il lotto.<\/p><ul><li><strong>3.6<\/strong> Nel caso in cui CHAXI riceva pi\u00f9 offerte scritte di pari importo per uno specifico lotto, quest\u2019ultimo sar\u00e0 aggiudicato al soggetto la cui offerta sia pervenuta per prima a CHAXI.<\/li><\/ul><ul><li><strong>3.7<\/strong> CHAXI nel formulare le offerte per conto del potenziale Acquirente terr\u00e0 conto della Riserva e delle altre offerte, in modo da ottenere l\u2019aggiudicazione del lotto al Prezzo pi\u00f9 conveniente.<\/li><\/ul><ul><li><strong>3.8<\/strong> Gli importi indicati nel modulo d\u2019offerta devono intendersi come importi massimi. CHAXI non accetta offerte illimitate ovvero prive di importo.<\/li><li><strong>3.9<\/strong> Ogni modulo d\u2019offerta deve contenere offerte per una sola asta. Offerte alternative possono essere accettate se viene specificata, tra il numero dei lotti, la parola \u201cOPPURE\u201d.<\/li><\/ul><ul><li><strong>3.10<\/strong> Dopo l\u2019asta, coloro che avranno lasciato offerte scritte dovranno tempestivamente controllare con CHAXI se la loro offerta \u00e8 andata a buon fine.<\/li><\/ul><ul><li><strong>3.11<\/strong> In caso di aggiudicazione di un lotto, nell\u2019ipotesi in cui il Venditore sia un professionista e l\u2019Acquirente sia un consumatore ai sensi dell\u2019art. 3 del Codice del Consumo, l\u2019Acquirente non disporr\u00e0 \u2013 ai sensi dell\u2019art. 59, comma 1, lettera m), del Codice del Consumo \u2013 del diritto di recesso previsto per i contratti a distanza in quanto il contratto di vendita \u00e8 concluso in occasione di un\u2019asta pubblica secondo la definizione fornita dall\u2019art. 45, comma 1, lettera o) del Codice del Consumo.<\/li><\/ul><p><strong>4.4 Offerte Telefoniche<\/strong><\/p><p><strong>4.4.1<\/strong> Mediante la compilazione e l\u2019invio dell\u2019apposito modulo di offerta (insieme alla documentazione in esso richiesta) allegato al catalogo d\u2019asta e caricato sul Sito \u00e8 possibile formulare offerte telefoniche.<\/p><ul><li><strong>4.2<\/strong> Il modulo di offerta dovr\u00e0 essere inviato a CHAXI almeno ventiquattro (24) ore prima dell\u2019asta.<\/li><\/ul><ul><li><strong>4.3<\/strong> Una volta ricevuto il modulo CHAXI provveder\u00e0 a contattare telefonicamente il potenziale Acquirente al numero di telefono indicato nel modulo.<\/li><\/ul><ul><li><strong>4.4<\/strong> Nel caso in cui CHAXI non riuscisse, per qualsiasi ragione, a contattare telefonicamente il potenziale Acquirente, potr\u00e0 effettuare per conto dello stesso offerte fino a un importo pari all\u2019offerta massima indicata nel modulo (\u201c<em>Covering Bid<\/em>\u201d). In questo caso, CHAXI nel formulare le offerte per conto del potenziale Acquirente terr\u00e0 conto della Riserva e delle altre offerte, in modo da ottenere l\u2019aggiudicazione del lotto al Prezzo pi\u00f9 conveniente.<\/li><\/ul><ul><li><strong>4.5<\/strong> CHAXI si riserva il diritto di registrare le offerte telefoniche e non assume alcuna responsabilit\u00e0, ad alcun titolo, nei confronti dei partecipanti all\u2019asta per problemi o inconvenienti relativi alla linea telefonica (a titolo di esempio, per interruzione o sospensione della linea telefonica).<\/li><\/ul><ul><li><strong>4.6<\/strong> CHAXI non accetta offerte telefoniche riferite a lotti la cui Stima minima di prevendita indicata in catalogo sia inferiore ad Euro 500,00.<\/li><\/ul><ul><li><strong>4.7<\/strong> In ogni caso, CHAXI non accetta offerte telefoniche per un importo inferiore alla Stima minima di prevendita.<\/li><\/ul><ul><li><strong>4.8<\/strong> Il personale di CHAXI \u00e8 disponibile ad effettuare telefonate in lingua inglese e francese.<\/li><\/ul><ul><li><strong>4.9<\/strong> In caso di aggiudicazione di un lotto, nell\u2019ipotesi in cui il Venditore sia un professionista e l\u2019Acquirente sia un consumatore ai sensi dell\u2019art. 3 del Codice del Consumo, l\u2019Acquirente non disporr\u00e0 \u2013 ai sensi dell\u2019art. 59, comma 1, lettera m), del Codice del Consumo \u2013 del diritto di recesso previsto per i contratti a distanza in quanto il contratto di vendita \u00e8 concluso in occasione di un\u2019asta pubblica secondo la definizione fornita dall\u2019art. 45, comma 1, lettera o) del Codice del Consumo.<\/li><\/ul><p><strong>4.5 Offerte via Internet<\/strong><\/p><ul><li><strong>5.1<\/strong> Almeno settantadue (72) ore prima la data dell\u2019asta, CHAXI comunicher\u00e0 sul Sito e\/o sul catalogo d\u2019asta, l\u2019asta in occasione della quale \u00e8 possibile formulare offerte anche via internet.<\/li><\/ul><ul><li><strong>5.2<\/strong> In caso di partecipazione all\u2019asta via internet il potenziale Acquirente avr\u00e0 la possibilit\u00e0 di vedere e ascoltare il banditore nonch\u00e9 fare offerte in tempo reale.<\/li><\/ul><ul><li><strong>5.3<\/strong> La partecipazione all\u2019asta via internet \u00e8 subordinata alla previa iscrizione al Sito e alla successiva registrazione all\u2019asta almeno ventiquattro (24) ore prima l\u2019inizio dell\u2019asta.<\/li><\/ul><ul><li><strong>5.4<\/strong> Una volta completata la registrazione al Sito, ciascun potenziale Acquirente riceve per email una password (che si impegna a custodire con cura e diligenza e a non diffondere ovvero comunicare a terzi) necessaria per accedere al Sito in qualit\u00e0 di utente registrato e per partecipare all\u2019asta.<\/li><\/ul><ul><li><strong>5.5<\/strong> Ciascun utente registrato \u00e8 responsabile per qualsiasi attivit\u00e0 compiuta attraverso il Sito tramite le proprie credenziali di accesso e si impegna a comunicare immediatamente a CHAXI qualsiasi uso illecito della sua password di accesso al Sito ovvero lo smarrimento della password. In questo caso, CHAXI provveder\u00e0 a comunicare all\u2019utente registrato una nuova password di accesso al Sito e la password precedente non potr\u00e0 pi\u00f9 essere utilizzata per accedere al Sito ovvero per partecipare alle aste.<\/li><\/ul><ul><li><strong>5.6<\/strong> CHAXI non garantisce che il Sito sia sempre operativo e che non vi si siano interruzioni durante la partecipazione all\u2019asta ovvero che il Sito e\/o il relativo server siano liberi da virus o da qualsiasi altro materiale dannoso o potenzialmente dannoso. Pertanto, salvo i casi di dolo o colpa grave, CHAXI non \u00e8 in alcun modo responsabile per eventuali problemi tecnici verificatisi in occasione dell\u2019asta (quali, a titolo esemplificativo e non esaustivo, rallentamenti nella navigazione Internet o il malfunzionamento del server che gestisce la partecipazione all\u2019asta via internet).<\/li><\/ul><ul><li><strong>5.7<\/strong> CHAXI non \u00e8 in alcun modo responsabile per qualsiasi danno ovvero inconveniente subito derivante dall\u2019uso non corretto del Sito ai sensi delle presenti Condizioni Generali di Vendita.<\/li><\/ul><ul><li><strong>5.8<\/strong> Ciascun potenziale Acquirente si impegna a non usare alcun software ovvero strumento di alcun tipo per influenzare ovvero interferire (anche solo potenzialmente) sull\u2019andamento dell\u2019asta e si impegna ad utilizzare il Sito e qualsiasi sua applicazione con correttezza e buona fede.<\/li><\/ul><ul><li><strong>5.9<\/strong> Qualora CHAXI abbia deciso di permettere la partecipazione all\u2019asta anche online, le presenti Condizioni Generali di Vendita disciplinano, anche l\u2019offerta in vendita e l\u2019aggiudicazione dei lotti tramite i siti \/ piattaforme internet attraverso i quali \u00e8 possibile formulare offerte. L\u2019asta online a cui si applicano le presenti Condizioni Generali di Vendita \u00e8 un\u2019asta pubblica (definita dall\u2019art. 45, comma 1, lett. o) del Codice del Consumo come il metodo di vendita in cui beni o servizi sono offerti dal professionista ai consumatori che partecipano o cui \u00e8 data la possibilit\u00e0 di partecipare all\u2019asta di persona, mediante una trasparente procedura competitiva di offerte gestita da una casa d\u2019aste e in cui l\u2019aggiudicatario \u00e8 vincolato all\u2019acquisto dei beni o servizi), ed \u00e8 la medesima asta pubblica a cui si pu\u00f2 partecipare in sala, ovvero al telefono o mediate una offerta scritta pre-asta.<\/li><\/ul><ul><li><strong>5.10<\/strong> I lotti acquistati tramite internet sono offerti e venduti da CHAXI che agisce in qualit\u00e0 di mandatario con rappresentanza del Venditore.<\/li><\/ul><ul><li><strong>5.11<\/strong> L\u2019offerta e la vendita da parte di CHAXI dei lotti offerti in vendita su internet costituiscono un contratto a distanza disciplinato dal Capo I, Titolo III (artt. 45 e ss.) del Codice del Consumo e dal Decreto Legislativo 9 aprile 2003, n. 70, contenente la disciplina del commercio elettronico.<\/li><\/ul><ul><li><strong>5.12<\/strong> In caso di aggiudicazione di un lotto, nell\u2019ipotesi in cui il Venditore sia un professionista e l\u2019Acquirente sia un consumatore ai sensi dell\u2019art. 3 del Codice del Consumo, l\u2019Acquirente non disporr\u00e0 \u2013 ai sensi dell\u2019arti. 59, comma 1, lettera m), del Codice del Consumo \u2013 del diritto di recesso previsto per i contratti a distanza in quanto il contratto di vendita \u00e8 concluso in occasione di un\u2019asta pubblica secondo la definizione fornita dall\u2019art. 45, comma 1, lettera o) del Codice del Consumo.<\/li><\/ul><p><strong>4.6 Offerte da parte dei Dipendenti<\/strong><\/p><ul><li><strong>6.1<\/strong> I dipendenti di CHAXI possono effettuare offerte in un\u2019asta di CHAXI solo se il dipendente non \u00e8 a conoscenza della Riserva e se effettua l\u2019offerta nel pieno rispetto delle regolamentazioni interne che regolano le offerte in asta dei dipendenti.<\/li><\/ul><ol start=\"5\"><li><strong> Obblighi di CHAXI nei confronti dell\u2019acquirente<\/strong><\/li><\/ol><ul><li><strong>1<\/strong> CHAXI agisce in nome e per conto del Venditore, in qualit\u00e0 di mandataria con rappresentanza del Venditore, ad eccezione dei casi in cui \u00e8 proprietaria in tutto o in parte di un lotto.<\/li><\/ul><ul><li><strong>2<\/strong> Su richiesta dell\u2019Acquirente, CHAXI potr\u00e0 fornire, a sua discrezione ed eventualmente a pagamento, un rapporto scritto (<em>condition report<\/em>) sulle condizioni del lotto.<\/li><\/ul><ul><li><strong>3<\/strong> Nel caso in cui, dopo la vendita in asta, un lotto risulti essere una Contraffazione, CHAXI rimborser\u00e0 all\u2019Acquirente che faccia richiesta di risoluzione del contratto di vendita, previa restituzione del lotto a CHAXI, l\u2019Importo totale dovuto a condizione che, non pi\u00f9 tardi di cinque (5) anni dalla data della vendita, l\u2019Acquirente:<\/li><li>comunichi a CHAXI per iscritto, entro tre (3) mesi dalla data in cui ha avuto una notizia che lo induca a ritenere che il lotto sia una Contraffazione, il numero del lotto, la data dell\u2019asta alla quale il lotto \u00e8 stato acquistato e i motivi per i quali l\u2019Acquirente ritenga che il lotto sia una Contraffazione;<\/li><li>sia in grado di riconsegnare a CHAXI il lotto, libero da rivendicazioni o da pretese da parte di terzi sorte dopo la data della vendita e il lotto sia nelle stesse condizioni in cui si trovava alla data della vendita;<\/li><li>fornisca a CHAXI le relazioni di due studiosi o esperti indipendenti e di riconosciuta competenza, in cui siano spiegate le ragioni per cui il lotto sia ritenuto una Contraffazione.<\/li><\/ul><ul><li><strong>4<\/strong> CHAXI si riserva il diritto di procedere alla risoluzione della vendita anche in assenza di una o pi\u00f9 delle condizioni sopra richieste, in tutto o in parte.<\/li><\/ul><ul><li><strong>5<\/strong> CHAXI non sar\u00e0 vincolata dai pareri forniti dall\u2019Acquirente e si riserva il diritto di richiedere il parere addizionale di altri esperti a sue proprie spese. Nel caso in cui CHAXI decida di risolvere la vendita, CHAXI avr\u00e0 facolt\u00e0 di rimborsare all\u2019Acquirente, in misura ragionevole, i costi da questo sostenuti per ottenere i pareri dei due esperti indipendenti e accettati sia da CHAXI che dall\u2019Acquirente.<\/li><\/ul><ul><li><strong>6<\/strong> L\u2019Acquirente non avr\u00e0 diritto di risolvere il contratto di vendita e CHAXI non effettuer\u00e0 il rimborso se:<\/li><li>la descrizione nel catalogo fosse conforme all\u2019opinione generalmente accettata di studiosi ed esperti alla data della vendita o indicasse come controversa l\u2019autenticit\u00e0 o l\u2019attribuzione del lotto; o<\/li><li>alla data della pubblicazione del catalogo la contraffazione del lotto poteva essere accertata soltanto svolgendo analisi generalmente ritenute inadeguate allo scopo o difficilmente praticabili, il cui costo era irragionevole o che avrebbero ragionevolmente potuto danneggiare o altrimenti comportare una diminuzione di valore del lotto.<\/li><\/ul><ol start=\"6\"><li><strong> Obblighi dell\u2019acquirente e responsabilit\u00e0 di CHAXI nei confronti degli acquirenti<\/strong><\/li><\/ol><ul><li><strong>1<\/strong> L\u2019Acquirente si impegna ad esaminare il lotto e la documentazione rilevante prima dell\u2019acquisto per verificarne la conformit\u00e0 alle descrizioni del catalogo e, se del caso, a richiedere il parere di uno studioso o di un esperto indipendente, per accertarne paternit\u00e0, autenticit\u00e0, provenienza, attribuzione, origine, data, et\u00e0, periodo, origine culturale ovvero fonte, condizione e completezza, qualit\u00e0, ivi compreso il prezzo o il valore.<\/li><\/ul><ul><li><strong>2<\/strong> Ogni rappresentazione scritta o verbale fornita da CHAXI, incluse quelle contenute nel catalogo, in relazioni, commenti o valutazioni concernenti qualsiasi carattere di un lotto, quale paternit\u00e0, autenticit\u00e0, provenienza, attribuzione, origine, data, et\u00e0, periodo, origine culturale ovvero fonte, condizione e completezza, qualit\u00e0, ivi compreso il prezzo o il valore, riflettono esclusivamente opinioni e possono essere riesaminate da CHAXI ed, eventualmente, modificate prima che il lotto sia offerto in vendita. Salvo il dolo e la colpa grave, CHAXI e i suoi dipendenti, collaboratori, amministratori o consulenti non sono responsabili degli errori o delle omissioni contenuti in queste rappresentazioni.<\/li><\/ul><ul><li><strong>3<\/strong> I lotti sono venduti \u201ccome visti e piaciuti\u201d, con espressa esclusione di ogni garanzia per vizi occulti e con ogni lacuna, difetto, imperfezione ed errore di descrizione.<\/li><\/ul><ul><li><strong>4<\/strong> Tutti i lotti, ivi compresi quelli che abbiano \u2013 in tutto o in parte \u2013 una natura elettrica o meccanica sono da considerarsi solamente sulla base del loro valore artistico, decorativo e\/o collezionistico e non sono da considerarsi funzionanti. Il funzionamento e la sicurezza dei lotti che abbiano, in tutto o in parte, una natura elettrica o meccanica non sono verificati prima della vendita e sono acquistati dall\u2019Acquirente a suo rischio e pericolo.<\/li><\/ul><ul><li><strong>5<\/strong> Le descrizioni dei cataloghi e dei <em>condition report<\/em> di cui all\u2019art. 5.2 che precede, sono meramente indicative e sono effettuate al solo scopo di identificare il lotto.<\/li><\/ul><ul><li><strong>6<\/strong> La mancanza di riferimenti espliciti nei cataloghi e nei <em>condition report<\/em> in merito alle condizioni del lotto non implica che il lotto sia privo di imperfezioni.<\/li><\/ul><ul><li><strong>7<\/strong> Salvo il caso di dolo o colpa grave, CHAXI ovvero i suoi dipendenti, collaboratori, amministratori o consulenti non saranno responsabili per atti od omissioni relativi alla preparazione o alla conduzione dell\u2019asta o per qualsiasi questione relativa alla fase preparatoria della vendita dei lotti.<\/li><\/ul><ul><li><strong>8<\/strong> Salvo il caso di dolo o colpa grave, l\u2019eventuale responsabilit\u00e0 di CHAXI ovvero dei suoi dipendenti, collaboratori, amministratori o consulenti nei confronti dell\u2019Acquirente in relazione all\u2019acquisto di un lotto da parte di quest\u2019ultimo \u00e8 limitata al Prezzo e alla Commissione di acquisto pagata dall\u2019Acquirente a CHAXI.<\/li><\/ul><ul><li><strong>9<\/strong> Le descrizioni di autovetture e motoveicoli, anche in relazione alla loro storia, alla loro et\u00e0, al modello, ai passaggi di propriet\u00e0, allo stato di conservazione e ad eventuali processi di restauro, a caratteristiche tecniche, ai componenti interni ed esterni, inclusi il numero del motore (<em>matching number<\/em> o meno) e del telaio dell\u2019autovettura \u2013 presenti in catalogo e\/o nel <em>condition report<\/em> sono fornite a titolo di orientamento per il potenziale Acquirente da CHAXI in buona fede sulla scorta delle indicazioni ed informazioni ricevute del Venditore, ma non devono essere ritenute esaustive e\/o verificate. Tutte le autovetture e i motoveicoli \u2013 insieme ai documenti rilevanti che li accompagnano \u2013 dovranno quindi essere esaminati in modo adeguato dal potenziale acquirente per poter completamente accertare il loro stato. L\u2019assenza di indicazione di un difetto, di un restauro o della presenza di una parte non originale non implica che tale difetto, restauro o presenza di una parte non originale non possano sussistere. Le descrizioni degli orologi e delle pietre preziose, anche in relazione allo stato di conservazione e ad eventuali restauri, presenti in catalogo e\/o nel <em>condition report<\/em> sono fornite a titolo di orientamento per il potenziale Acquirente da CHAXI in buona fede sulla scorta delle indicazioni ed informazioni ricevute del Venditore, ma non devono essere ritenute esaustive e\/o verificate. Tutti gli orologi e le pietre preziose dovranno quindi essere esaminati in modo adeguato dal potenziale acquirente per poter completamente accertare il loro stato. L\u2019assenza di indicazione di un difetto, di un restauro o della presenza di una parte non originale non implica che tale difetto, restauro o presenza di una parte non originale non possano sussistere. Nel caso di orologi da polso dichiarati dal produttore come impermeabili, il loro esame pu\u00f2 aver richiesto la loro apertura: CHAXI suggerisce pertanto che l\u2019Acquirente, prima di utilizzarli in condizioni di presenza d\u2019acqua, li porti ad un centro autorizzato per la verifica della tenuta. I cinturini in materiale organico eventualmente presenti sono associati alle casse in fase di prevendita a puro scopo di presentazione: i potenziali Acquirenti sono consapevoli che l\u2019importazione in Paesi stranieri di materiali provenienti da specie in pericolo di estinzione, quali, a titolo di puro esempio, tartaruga ed avorio, \u00e8 soggetta alla normativa internazionale CITES. Il potenziale Acquirente dovr\u00e0 quindi informarsi adeguatamente in fase preliminare relativamente a tali restrizioni, se intende partecipare all\u2019asta per un lotto che contenga, anche solo in parte, materiali di questa tipologia.<\/li><\/ul><ul><li><strong>10<\/strong> In caso di aggiudicazione di un\u2019autovettura e\/o di un motoveicolo, ai sensi e per gli effetti della normativa anche regolamentare rilevante, l\u2019Acquirente si impegna ad avviare e gestire, tramite un\u2019agenzia competente indicata da CHAXI, a propria cura e spese, il procedimento di passaggio di propriet\u00e0 e\/o, se del caso, il procedimento di immatricolazione, entro e non oltre quindici (15) giorni dalla data di aggiudicazione del Lotto. Il tutto fatto salvo quanto previsto dal successivo art. 7.11.<\/li><\/ul><ul><li><strong>11<\/strong> In caso di definitiva esportazione all\u2019estero di autoveicoli e\/o di motoveicoli immatricolati in Italia, ai sensi e per gli effetti della normativa anche regolamentare rilevante, l\u2019Acquirente si impegna a richiedere all\u2019ufficio competente la cancellazione dall\u2019archivio nazionale dei veicoli e dal Pubblico registro automobilistico, restituendo la targa e la carta di circolazione del Lotto entro e non oltre 15 (quindici giorni) dall\u2019aggiudicazione del Lotto.<\/li><\/ul><ol start=\"7\"><li><strong> Pagamento<\/strong><\/li><\/ol><ul><li><strong>1<\/strong> In caso di aggiudicazione, l\u2019Acquirente \u00e8 tenuto a pagare a CHAXI l\u2019Importo totale dovuto immediatamente \u2013 e comunque entro e non oltre cinque (5) giorni \u2013 dalla conclusione dell\u2019asta.<\/li><\/ul><ul><li><strong>2<\/strong> Nel caso in cui il lotto sia stato oggetto della dichiarazione di cui all\u2019art. 4.1.14 che precede, l\u2019Acquirente si impegna a corrispondere l\u2019Importo totale dovuto al decorso del termine per l\u2019esercizio della prelazione da parte del Ministero competente.<\/li><\/ul><ul><li><strong>3<\/strong> La fatturazione del Prezzo all\u2019Acquirente sar\u00e0 di competenza esclusiva del Venditore.<\/li><\/ul><ul><li><strong>4<\/strong> Il pagamento della Commissione di acquisto e delle eventuali Spese potr\u00e0 essere effettuato mediante contanti, assegno circolare, assegno bancario, bonifico, Bancomat o Carta di Credito (American Express, Visa o Mastercard) o Paypal.<\/li><\/ul><ul><li><strong>5<\/strong> CHAXI pu\u00f2 accettare pagamenti singoli o multipli in contanti solo per importi inferiori a euro 999,99.<\/li><\/ul><ul><li><strong>6<\/strong> Le coordinate bancarie per i bonifici sono le seguenti:<\/li><\/ul><p>CHAXI GALLERY<\/p><p>banca: BANCO BPER DI CHAKHSI IMANE<\/p><p>IBAN numero IT16I0538755132000042805949 SWIFT\/BIC numero BPMOIT22XXX<\/p><ul><li><strong>7<\/strong> Nel caso di bonifico, nella causale dovr\u00e0 essere indicato nome e cognome dell\u2019Acquirente e il numero della fattura.<\/li><\/ul><ul><li><strong>8<\/strong> Il pagamento mediante Bancomat, American Express, Visa o Mastercard pu\u00f2 essere disposto solo dal titolare della carta ovvero, nel caso di pagamento mediante PayPal, dal titolare del relativo conto.<\/li><\/ul><ul><li><strong>9<\/strong> CHAXI si riserva la facolt\u00e0 di controllare la provenienza dei pagamenti ricevuti e di non accettare pagamenti ricevuti da persone differenti dall\u2019Acquirente.<\/li><\/ul><ul><li><strong>10<\/strong> In limitate circostanze e comunque previo il consenso del Venditore, CHAXI potr\u00e0 concedere agli Acquirenti che ritenga affidabili la facolt\u00e0 di pagare i lotti a cadenze dilazionate. Le modalit\u00e0 di pagamento dilazionato dovranno essere definite prima della vendita. Prima di stabilire se concedere o meno pagamenti dilazionati, CHAXI pu\u00f2 chiedere referenze sull\u2019affidabilit\u00e0 dell\u2019Acquirente e documentazione sulla sua identit\u00e0 e residenza.<\/li><\/ul><ul><li><strong>11<\/strong> Anche ai sensi e per gli effetti di quanto previsto all\u2019art. 1523 c.c., il trasferimento della propriet\u00e0 del lotto dal Venditore all\u2019Acquirente avverr\u00e0 soltanto al momento del pagamento da parte dell\u2019Acquirente dell\u2019Importo totale dovuto.<\/li><\/ul><ul><li><strong>12<\/strong> In caso di mancato o ritardato pagamento da parte dell\u2019Acquirente \u2013 nel termine di cui all\u2019art. 7.1. che precede \u2013 in tutto o in parte, dell\u2019Importo totale dovuto, CHAXI ha diritto, a propria scelta, di chiedere l\u2019adempimento ovvero di risolvere il contratto di vendita a norma dell\u2019art. 1456 c.c., salvo in ogni caso il diritto al risarcimento dei danni, nonch\u00e9 la facolt\u00e0 di far vendere il lotto per conto ed a spese dell\u2019Acquirente, a norma dell\u2019art. 1515 c.c.<\/li><\/ul><ul><li><strong>13<\/strong> In caso di ritardo nel pagamento dell\u2019Importo totale dovuto per un periodo superiore a cinque (5) giorni lavorativi dalla data dell\u2019asta, CHAXI potr\u00e0 depositare il lotto presso un depositario terzo a rischio e spese dell\u2019Acquirente. Nonch\u00e9 di addebitare all\u2019Acquirente e di trattenere a proprio credito interessi moratori in misura pari al tasso previsto dalla legge Euribor a 3 mesi maggiorato di uno spread del cinque per cento (5%), salvo il diritto di CHAXI al risarcimento del maggior danno.<\/li><\/ul><ul><li><strong>14<\/strong> In caso di mancato o ritardato pagamento da parte dell\u2019Acquirente, CHAXI potr\u00e0 rifiutare qualsiasi offerta fatta dall\u2019Acquirente o da un suo rappresentante nel corso di aste successive o chiedere all\u2019Acquirente di depositare una somma di denaro, a titolo di garanzia, prima di accettare offerte.<\/li><\/ul><ul><li><strong>15<\/strong> CHAXI ha la facolt\u00e0 di compensare ogni somma dovuta, a qualsiasi titolo, all\u2019Acquirente con ogni somma dovuta da quest\u2019ultimo, a qualsiasi titolo a CHAXI.<\/li><\/ul><ul><li><strong>16<\/strong> Orario di cassa: Luned\u00ec &#8211; Venerd\u00ec 10.00-13.00; 14.00-17.30.<\/li><\/ul><ol start=\"8\"><li><strong> Consegna e ritiro del lotto<\/strong><\/li><\/ol><ul><li><strong>1<\/strong> La consegna del lotto avverr\u00e0 presso la sede di CHAXI non oltre cinque (5) giorni lavorativi dal giorno della aggiudicazione.<\/li><\/ul><ul><li><strong>2<\/strong> Il lotto sar\u00e0 consegnato solo ad avvenuto pagamento dell\u2019Importo totale dovuto all\u2019Acquirente ovvero a soggetto terzo munito di delega scritta rilasciata da quest\u2019ultimo.<\/li><\/ul><ul><li><strong>3<\/strong> Al momento della consegna del lotto, CHAXI richieder\u00e0 all\u2019Acquirente o al terzo in caricato un documento attestante la sua identit\u00e0.<\/li><\/ul><ul><li><strong>4<\/strong> Prima di organizzare il ritiro del lotto, si prega di controllare con CHAXI dove \u00e8 conservato il lotto.<\/li><\/ul><ul><li><strong>5<\/strong> Nell\u2019ipotesi di morte, interdizione, inabilitazione, estinzione\/ cessazione, per qualsiasi motivo, dell\u2019Acquirente, debitamente comunicata a CHAXI, quest\u2019ultima acconsentir\u00e0 a riconsegnare il lotto previo accordo di tutti gli aventi causa dell\u2019Acquirente ovvero secondo le modalit\u00e0 stabilite dall\u2019autorit\u00e0 giudiziaria.<\/li><\/ul><ul><li><strong>6<\/strong> Qualora l\u2019Acquirente non ritiri il lotto entro cinque (5) giorni lavorativi dal giorno della vendita, CHAXI avr\u00e0 diritto di:<\/li><\/ul><p><strong>(a)<\/strong> addebitare all\u2019Acquirente un importo pari all\u2019uno per cento (1%) del Prezzo per ogni mese di ritardo nel ritiro del lotto, a partire dal quinto giorno lavorativo successivo alla vendita; ovvero<\/p><p><strong>(b)<\/strong> depositare il lotto presso un depositario terzo a rischio e spese dell\u2019Acquirente.<\/p><ol start=\"9\"><li><strong> Trasferimento del rischio<\/strong><\/li><\/ol><ul><li><strong>1<\/strong> Un lotto acquistato \u00e8 interamente a rischio dell\u2019Acquirente a partire dalla data pi\u00f9 antecedente fra quelle in cui l\u2019Acquirente:<\/li><\/ul><p><strong>(a)<\/strong> prende in consegna il lotto acquistato; o<\/p><p><strong>(b)<\/strong> paga l\u2019Importo totale dovuto per il lotto; ovvero<\/p><p><strong>(c) <\/strong>dalla data in cui decorre il termine di pagamento di cinque (5) giorni lavorativi dal giorno<\/p><p>\u00a0\u00a0\u00a0\u00a0 dell\u2019aggiudicazione.<\/p><ul><li><strong>2<\/strong> L\u2019Acquirente sar\u00e0 risarcito per qualsiasi perdita o danno del lotto che si verifichi dopo la vendita ma prima del trasferimento del rischio, ma il risarcimento non potr\u00e0 superare, salvo il caso di dolo o colpa grave, il Prezzo oltre alla Commissione di acquisto ricevuta da CHAXI.<\/li><\/ul><ul><li><strong>3<\/strong> Salvo il caso di dolo o colpa grave, in nessun caso CHAXI si assume la responsabilit\u00e0 per la perdita o danni causati alle cornici o al vetro che contengono o coprono stampe, dipinti o altre opere a meno che la cornice o\/e il vetro non costituiscano il lotto venduto all\u2019asta.<\/li><\/ul><ul><li><strong>4<\/strong> In nessun caso CHAXI sar\u00e0 responsabile per la perdita o il danneggiamento verificatisi a seguito di un qualsiasi intervento (compresi interventi di restauro, interventi sulle cornici e interventi di pulitura) da parte di esperti indipendenti incaricati da CHAXI con il consenso del Venditore per la perdita o il danneggiamento causati o derivanti, direttamente o indirettamente, da:<\/li><\/ul><p><strong>(a)<\/strong> cambiamenti di umidit\u00e0 o temperatura;<\/p><p><strong>(b)<\/strong> normale usura o graduale deterioramento derivanti da interventi sul lotto e\/o da vizi o difetti<\/p><p>\u00a0\u00a0\u00a0\u00a0 occulti (inclusi i tarli del legno);<\/p><p><strong>(c)<\/strong> errori di trattamento;<\/p><p><strong>(d)<\/strong> guerra, fissione nucleare, contaminazione radioattiva, armi chimiche, biochimiche o elettro-<\/p><p>\u00a0\u00a0\u00a0\u00a0 magnetiche;<\/p><p><strong>(e)<\/strong> atti di terrorismo; e <strong>(f)<\/strong> altri eventi di forza maggiore.<\/p><ol start=\"10\"><li><strong> Spedizione<\/strong><\/li><\/ol><ul><li><strong>1<\/strong> Su richiesta scritta dell\u2019Acquirente, CHAXI potr\u00e0 organizzare l\u2019imballaggio e la spedizione del lotto a condizione che l\u2019Acquirente:<\/li><\/ul><p>abbia interamente pagato l\u2019Importo totale dovuto;<\/p><p>fornisca a CHAXI eventuali attestati di libera circolazione ovvero licenze di esportazione o qualunque eventuale attestazione e\/o certificazione a tal fine necessari.<\/p><ul><li><strong>2 Saldo diverso accordo con l\u2019Acquirente:<\/strong><\/li><li>le spese di imballaggio e spedizione sono a carico e cura dell\u2019Acquirente che potr\u00e0 richiedere, almeno ventiquattro (24) ore prima dell\u2019inizio dell\u2019asta, preventivi di spesa qualora intenda affidare a CHAXI l\u2019imballaggio e la spedizione del lotto;<\/li><li>la copertura assicurativa volta a coprire il rischio di perdite e\/o danni (anche parziali) che il lotto pu\u00f2 subire durante il trasporto dovr\u00e0 essere concordata fra l\u2019Acquirente ed il trasportatore senza alcuna responsabilit\u00e0 per CHAXI;<\/li><li>il costo della copertura assicurativa sar\u00e0 a spese dell\u2019Acquirente.<\/li><\/ul><ul><li><strong>3<\/strong> L\u2019imballaggio e la spedizione del lotto all\u2019Acquirente sono interamente a rischio e a carico dell\u2019Acquirente e CHAXI non si assume alcuna responsabilit\u00e0 per azioni od omissioni degli addetti all\u2019imballaggio o dei trasportatori.<\/li><\/ul><ol start=\"11\"><li><strong> Esportazione dal territorio della Repubblica italiana<\/strong><\/li><\/ol><ul><li><strong>1<\/strong> L\u2019esportazione di beni culturali al di fuori del territorio della Repubblica italiana \u00e8 assoggettata alla disciplina prevista dal Codice Urbani. L\u2019esportazione di beni culturali al di fuori del territorio dell\u2019Unione Europea \u00e8 altres\u00ec assoggettata alla disciplina prevista dal Regolamento CE n. 116\/2009 del 18 dicembre 2008 e dal Regolamento UE di esecuzione della Commissione n. 1081\/2012.<\/li><\/ul><ul><li><strong>2<\/strong> L\u2019esportazione dal territorio della Repubblica italiana di un lotto pu\u00f2 essere soggetta al rilascio di un attestato di libera circolazione ovvero di una licenza di esportazione.<\/li><\/ul><ul><li><strong>3<\/strong> Il rilascio dell\u2019attestato di libera circolazione ovvero e\/o della licenza di esportazione \u00e8 a carico dell\u2019Acquirente. Il mancato rilascio o il ritardo nel rilascio dell\u2019attestato di libera circolazione e\/o della licenza di esportazione non costituisce una causa di risoluzione o di annullamento della vendita, n\u00e9 giustifica il ritardato pagamento da parte dell\u2019Acquirente dell\u2019Importo totale dovuto.<\/li><\/ul><ol start=\"12\"><li><strong> Specie protette<\/strong><\/li><\/ol><ul><li><strong>1<\/strong> Tutti i lotti costituiti da o contenenti parti di piante o animali (ad esempio corallo, coccodrillo, avorio, osso di balena, tartaruga), indipendentemente dall\u2019et\u00e0 e dal valore, potrebbero richiedere una licenza o un certificato prima dell\u2019esportazione e richiedere ulteriori licenze o certificati per l\u2019importazione nei paesi Extra UE. Si prega di notare che l\u2019aver ottenuto la licenza o il certificato in importazione non garantisce alcuna licenza o certificato per l\u2019esportazione e vice versa. CHAXI consiglia ai potenziali Acquirenti di controllare le proprie legislazioni circa i requisiti necessari per le importazioni nel proprio Paese di beni fatti o contenenti specie protette. \u00c8 responsabilit\u00e0 dell\u2019Acquirente ottenere tali licenze\/certificati di importazione o esportazione, cos\u00ec come ogni altro documento richiesto prima di effettuare qualsiasi offerta. Si prega di fare riferimento all\u2019art. 11 delle Condizioni Generali di Vendita.<\/li><\/ul><p><strong>\u00a0<\/strong><\/p><ol start=\"13\"><li><strong> Terminologia esemplificativa<\/strong><\/li><\/ol><ul><li><strong>1<\/strong> Si prega di prestate attenzione alla seguente terminologia esemplificativa:<\/li><\/ul><ul><li>\u201cMICHELANGELO MERISI\u201d A parere di CHAXI opera dell\u2019artista (quando non \u00e8 conosciuto il primo nome dell\u2019artista sia che il cognome venga preceduto da una serie di asterischi, sia da una iniziale o no, indica che l\u2019opera \u00e8 dell\u2019artista nominato).<\/li><li>\u201cATTRIBUITO A MICHELANGELO MERISI\u201d \u00c8 opinione di CHAXI che sia probabilmente opera dell\u2019artista, ma con meno sicurezza che nella categoria precedente.<\/li><li>\u201cBOTTEGA DI MICHELANGELO MERISI\u201d A parere di CHAXI \u00e8 di una mano sconosciuta della bottega dell\u2019artista, che pu\u00f2 essere stata eseguita sotto la direzione dell\u2019artista.<\/li><li>\u201cCERCHIA DI MICHELANGELO MERISI\u201d A parere di CHAXI un\u2019opera di mano non identificata, ma distinta; strettamente associata con il suddetto artista, ma non necessariamente suo allievo.<\/li><li>\u201cSTILE DI\/SEGUACE DI MICHELANGELO MERISI\u201d A parere di CHAXI opera di un pittore che lavora nello stile dell\u2019artista, contemporaneo o quasi contemporaneo, ma non necessariamente suo allievo.<\/li><li>\u201cMANIERA DI MICHELANGELO MERISI\u201d A parere di CHAXI una opera nello stile dell\u2019artista di epoca pi\u00f9 tarda.<\/li><li>\u201cDA MICHELANGELO MERISI\u201d A parere di CHAXI una copia di un dipinto conosciuto dell\u2019artista.<\/li><li>\u201cIN STILE\u2026\u201d A parere di CHAXI opera nello stile citato pur essendo eseguita in epoca successiva.<\/li><\/ul><ul><li><strong>2<\/strong> Il termine firmato e\/o datato e\/o iscritto, significa che a parere di CHAXI la firma e\/o la data e\/o l\u2019iscrizione sono di mano dell\u2019artista.<\/li><\/ul><ul><li><strong>3<\/strong> Il termine recante firma e\/o data e\/o iscrizione, significa che a parere di CHAXI queste sembrano aggiunte o di altra mano.<\/li><\/ul><ul><li><strong>4<\/strong> Le dimensioni date sono, nell\u2019ordine, altezza, base ed eventualmente profondit\u00e0.<\/li><\/ul><ul><li><strong>5<\/strong> I dipinti e le fotografie non s\u2019intendono incorniciati se non altrimenti specificato.<\/li><\/ul><ol start=\"14\"><li><strong> Contatti<\/strong><\/li><\/ol><ul><li><strong>1<\/strong> Il potenziale Acquirente e l\u2019Acquirente pu\u00f2 richiedere qualsiasi informazione e\/o inviare comunicazioni e\/o presentare reclami contattando CHAXI con le seguenti modalit\u00e0:<\/li><\/ul><p><strong>(I)<\/strong> compilando e inviando il modulo disponibile nella sezione \u201cContatti\u201d del Sito www.chaxigallery.com;<\/p><p><strong>(II)<\/strong> per posta, scrivendo a CHAXI GALLERY, Via Pietro Cismondi, 15 \u2013 20154 \u2013 Roncadelle (BS), Italia;<\/p><p><strong>(III)<\/strong> al seguente numero telefonico: (+39) 030 4195899<\/p><p><strong>(IV)<\/strong> al seguente numero per whatsapp (+39) 3287188597.<\/p><ul><li><strong>2<\/strong> CHAXI risponder\u00e0 ai reclami presentati entro cinque (5) giorni lavorativi dal ricevimento degli stessi.<\/li><\/ul><ul><li><strong>3<\/strong> Per assistenza durante la partecipazione all\u2019asta online pu\u00f2 contattare CHAXI al seguente indirizzo email: info@chaxigallery.com<\/li><\/ul><p>\u00a0\u00a0\u00a0 ovvero al seguente numero telefonico: +39 030 4195899.<\/p><ol start=\"15\"><li><strong> Garanzia legale e di conformit\u00e0<\/strong><\/li><\/ol><ul><li><strong>1<\/strong> Nell\u2019ipotesi in cui il Venditore sia un professionista e l\u2019Acquirente sia un consumatore ai sensi dell\u2019art. 3 del Codice del Consumo e che il lotto aggiudicato possa considerarsi un \u201cbene di consumo\u201d ai sensi degli artt. 128 e ss. del Codice del Consumo, a detti lotti \u2013 venduti tramite CHAXI \u2013 si applica la garanzia legale di conformit\u00e0 prevista dagli artt. 128-135 del Codice del Consumo (Garanzia Legale).<\/li><\/ul><ul><li><strong>2<\/strong> La Garanzia Legale \u00e8 riservata ai consumatori. Essa, pertanto, trova applicazione, solo a chi abbia acquistato un lotto per scopi estranei all\u2019attivit\u00e0 imprenditoriale, commerciale, artigianale o professionale eventualmente svolta.<\/li><\/ul><ul><li><strong>3<\/strong> Il Venditore \u00e8 responsabile nei confronti dell\u2019Acquirente consumatore per qualsiasi difetto di conformit\u00e0 esistente al momento della consegna del lotto \u201cbene di consumo\u201d che si manifesti entro due anni da tale consegna. Il difetto di conformit\u00e0 deve essere denunciato al Venditore, a pena di decadenza dalla garanzia, nel termine di due mesi dalla data in cui \u00e8 stato scoperto. Salvo prova contraria, si presume che i difetti di conformit\u00e0 che si manifestano entro i sei mesi dalla consegna del prodotto esistessero gi\u00e0 a tale data, a meno che tale ipotesi sia incompatibile con la natura del prodotto o con la natura del difetto di conformit\u00e0. A partire dal settimo mese successivo alla consegna del prodotto, sar\u00e0 invece onere del consumatore provare che il difetto di conformit\u00e0 esisteva gi\u00e0 al momento della consegna dello stesso. Per poter usufruire della Garanzia Legale, il consumatore dovr\u00e0 quindi fornire innanzitutto prova della data dell\u2019acquisto e della consegna del lotto. \u00c8 opportuno, quindi, che il consumatore, a fini di tale prova, conservi la conferma d\u2019ordine o la fattura di acquisto, o il DDT ovvero qualsiasi altro documento che possa attestare la data di effettuazione dell\u2019acquisto e la data della consegna.<\/li><\/ul><ul><li><strong>4<\/strong> Per difetto di conformit\u00e0 di un lotto si rimanda a quanto indicato all\u2019art. 129, comma 2, del Codice del Consumo. Sono esclusi dal campo di applicazione della Garanzia Legale eventuali difetti determinati da fatti accidentali o da responsabilit\u00e0 dell\u2019Acquirente consumatore ovvero del lotto difforme rispetto alla sua destinazione d\u2019uso. A tal proposito, si precisa che tutti i lotti, ivi compresi quelli che abbiano \u2013 in tutto o in parte \u2013 una natura elettrica o meccanica sono da considerarsi solamente sulla base del loro valore artistico, decorativo e\/o collezionistico e non sono da considerarsi funzionanti.<\/li><\/ul><ul><li><strong>5<\/strong> In caso di difetto di conformit\u00e0 debitamente denunciato nei termini, l\u2019Acquirente consumatore ha diritto: (i) in via primaria, alla riparazione o sostituzione gratuita del lotto, a sua scelta, salvo che il rimedio richiesto sia oggettivamente impossibile o eccessivamente oneroso rispetto all\u2019altro; (ii) in via secondaria (nel caso cio\u00e8 in cui la riparazione o la sostituzione siano impossibili o eccessivamente onerose ovvero la riparazione o la sostituzione non siano state realizzate entro termini congrui ovvero la riparazione o la sostituzione precedentemente effettuate abbiano arrecato notevoli inconvenienti al consumatore) alla riduzione del prezzo o alla risoluzione del contratto, a sua scelta. Il rimedio richiesto \u00e8 eccessivamente oneroso se impone al Venditore spese irragionevoli in confronto ai rimedi alternativi che possono essere esperiti, tenendo conto (i) del valore che il lotto avrebbe se non vi fosse il difetto di conformit\u00e0; (ii) dell\u2019entit\u00e0 del difetto di conformit\u00e0; (iii) dell\u2019eventualit\u00e0 che il rimedio alternativo possa essere esperito senza notevoli inconvenienti per il consumatore.<\/li><\/ul><p><strong>\u00a0<\/strong><\/p><ul><li><strong>6<\/strong> Nel caso in cui il lotto, nel corso del periodo di validit\u00e0 della Garanzia Legale, manifesti quello che potrebbe essere un difetto di conformit\u00e0, l\u2019Acquirente consumatore pu\u00f2 contattare il CHAXI al numero indicato all\u2019art. 14. CHAXI dar\u00e0 tempestivo riscontro alla comunicazione del presunto difetto di conformit\u00e0 e indicher\u00e0 al consumatore la specifica procedura da seguire.<\/li><\/ul><ol start=\"16\"><li><strong> Legge applicabile e giurisdizione<\/strong><\/li><\/ol><ul><li><strong>1<\/strong> Le presenti Condizioni Generali di Vendita sono regolate dalla legge italiana.<\/li><\/ul><ul><li><strong>2<\/strong> Per ogni controversia relativa all\u2019applicazione, esecuzione e interpretazione delle Condizioni Generali di Vendita \u00e8 competente il foro di Milano.<\/li><\/ul><ul><li><strong>3<\/strong> \u00c8 fatta salva la applicazione agli Acquirenti che siano consumatori ai sensi dell\u2019art. 3 del Codice del Consumo che non abbiano la loro residenza abituale in Italia delle disposizioni eventualmente pi\u00f9 favorevoli e inderogabili previste dalla legge del Paese in cui essi hanno la loro residenza abituale. Per ogni controversia relativa all\u2019applicazione, esecuzione e interpretazione delle Condizioni Generali di Vendita \u00e8 competente il foro del luogo in cui l\u2019Acquirente consumatore risiede o ha eletto domicilio.<\/li><\/ul><ul><li><strong>4<\/strong> L\u2019Acquirente consumatore che risiede in uno stato membro dell\u2019Unione Europea diverso dall\u2019Italia, pu\u00f2, inoltre, accedere, per ogni controversia relativa all\u2019applicazione, esecuzione e interpretazione delle presenti Condizioni Generali di Vendita, al procedimento Europeo istituito per le controversie di modesta entit\u00e0, dal Regolamento (CE) n. 861\/2007 del Consiglio, dell\u201911 luglio 2007, a condizione che il valore della controversia non ecceda, esclusi gli interessi, i diritti e le spese, Euro 2.000,00. Il testo del regolamento \u00e8 reperibile sul sito eur-lex.europa.eu.<\/li><\/ul><ul><li><strong>5<\/strong> Ai sensi dell\u2019art. 141-sexies, comma 3, del Codice del Consumo, CHAXI informa l\u2019utente che rivesta la qualifica di consumatore di cui all\u2019art. 3, comma 1, lett. a) del Codice del Consumo, che, nel caso in cui egli abbia presentato un reclamo direttamente a CHAXI, a seguito del quale non sia stato tuttavia possibile risolvere la controversia cos\u00ec insorta, CHAXI fornir\u00e0 le informazioni in merito all\u2019organismo o agli organismi di Alternative Dispute Resolution per la risoluzione extragiudiziale delle controversie relative ad obbligazioni derivanti da un contratto concluso in base alle presenti Condizioni Generali di Vendita (cc.dd. organismi ADR, come indicati agli artt. 141-bis e ss. Codice del Consumo), precisando se intenda avvalersi o meno di tali organismi per risolvere la controversia stessa. CHAXI informa inoltre l\u2019utente che rivesta la qualifica di consumatore di cui all\u2019art. 3, comma 1, lett. a), del Codice del Consumo che \u00e8 stata istituita una piattaforma europea per la risoluzione on-line delle controversie dei consumatori (c.d. piattaforma ODR). La piattaforma ODR \u00e8 consultabile al seguente indirizzo http:\/\/ ec.europa.eu\/consumers\/odr\/; attraverso la piattaforma ODR l\u2019utente consumatore potr\u00e0 consultare l\u2019elenco degli organismi ADR, trovare il link al sito di ciascuno di essi e avviare una procedura di risoluzione on-line della controversia in cui sia coinvolto.<\/li><\/ul><ol start=\"17\"><li><strong> Informativa sul trattamento dei dati personali<\/strong><\/li><\/ol><ul><li><strong>1<\/strong> Ai sensi dell\u2019art. 13 del Regolamento (UE) n. 2016\/679 (\u201cGDPR\u201d), CHAXI \u2013 in qualit\u00e0 di titolare del trattamento (di seguito, anche, \u201cTitolare\u201d) \u2013 La informa che i dati personali (\u201cDati\u201d) da Lei conferiti a CHAXI saranno trattati in modo lecito e secondo correttezza da quest\u2019ultima principalmente con l\u2019ausilio di mezzi elettronici, automatizzati e\/o di videoregistrazione (secondo le modalit\u00e0 e con gli strumenti idonei a garantire la sicurezza e la riservatezza dei Dati stessi) per: (a) esigenze funzionali all\u2019esecuzione dei contratti di cui Lei \u00e8 parte o per l\u2019adozione di misure precontrattuali adottate su Sua richiesta, (b) esigenze gestionali del rapporto con i venditori ed i compratori (quali, ad es., amministrazione di proventi di vendita, fatture, spedizioni), (c) verifiche e valutazioni sul rapporto di vendita all\u2019asta nonch\u00e9 sui rischi ad esso connessi, (d) per adempimenti di obblighi fiscali, contabili, legali e\/o di disposizioni di organi pubblici, ovvero, (e) per finalit\u00e0 previste dalla vigente normativa in materia di antiriciclaggio ai sensi del D.lgs. 231\/2007 e successive modifiche, (f) con riferimento ai sistemi di videosorveglianza, per finalit\u00e0 di tutela della sicurezza delle persone e di tutela del patrimonio aziendale, (g) per l\u2019accertamento, l\u2019esercizio o la difesa di un diritto in sede giudiziaria, (h) per l\u2019invio di comunicazioni commerciali su prodotti e servizi analoghi a quelli gi\u00e0 acquistati (c.d. \u201csoft spam\u201d), (i) con il Suo consenso, per l\u2019invio di materiale pubblicitario ed informativo su prodotti e servizi di CHAXI a mezzo di sistemi automatizzati, quali e-mail, fax, sms, MMS e Whatsapp o a mezzo del servizio postale o di chiamate telefoniche con operatore, (l) per effettuare attivit\u00e0 di profilazione finalizzate all\u2019esecuzione delle attivit\u00e0 di cui alle precedenti lettere (h) e (i).<\/li><\/ul><ul><li><strong>2<\/strong> Il conferimento dei Dati per le finalit\u00e0 di cui all\u2019art. 17.1, lettere (a), (b), (d), (e), non richiede il Suo consenso in quanto \u00e8 necessario affinch\u00e9 il Titolare possa adempiere agli obblighi contrattuali e legali cui \u00e8 soggetto, dai sensi dell\u2019art. 6 comma 1, lett. b) e c) del GDPR.<\/li><\/ul><ul><li><strong>3<\/strong> Il trattamento dei Dati per le finalit\u00e0 di cui all\u2019art. 17.1, lettere (c), (f), (g), (h), non richiede il Suo consenso, in quanto \u00e8 necessario al perseguimento del legittimo interesse del Titolare ai sensi dell\u2019art. 6, comma 1, lett. f) del GDPR.<\/li><\/ul><ul><li><strong>4<\/strong> Il trattamento dei Dati per le finalit\u00e0 di cui all\u2019art. 17.1, lettere (i) e (l) richiede invece il Suo consenso, ai sensi dell\u2019art. 6, comma 1, lett. a) del GDPR. Il conferimento di tali Dati per la suddetta finalit\u00e0 \u00e8 facoltativo; il loro mancato conferimento comporter\u00e0 unicamente l\u2019impossibilit\u00e0 per CHAXI di svolgere le attivit\u00e0 indicate. Per tali finalit\u00e0 CHAXI raccoglier\u00e0 il Suo consenso con modalit\u00e0 elettroniche e\/o cartacee, per esempio tramite il Sito oppure l\u2019apposita modulistica.<\/li><\/ul><ul><li><strong>5<\/strong> Il conferimento dei Dati \u00e8 facoltativo. Tuttavia, il mancato conferimento dei Dati per le finalit\u00e0 da (a) a (g) comporter\u00e0 l\u2019impossibilit\u00e0 di partecipare all\u2019asta ovvero il corretto adempimento degli obblighi gravanti su CHAXI; il mancato conferimento dei Dati per le finalit\u00e0 da (h) a (l) comporter\u00e0 unicamente l\u2019impossibilit\u00e0 per CHAXI di svolgere le attivit\u00e0 indicate.<\/li><\/ul><ul><li><strong>6<\/strong> I Dati verranno trattati dai dipendenti o collaboratori di CHAXI in qualit\u00e0 di persone autorizzate al trattamento.<\/li><\/ul><ul><li><strong>7<\/strong> I Suoi Dati potranno essere comunicati, inoltre, ai seguenti soggetti, i quali saranno designati da CHAXI come responsabili del trattamento oppure agiranno in qualit\u00e0 di titolari autonomi:<\/li><li>tutti quei soggetti (ivi incluse le Pubbliche Autorit\u00e0) che hanno accesso ai dati personali in forza di provvedimenti normativi o amministrativi;<\/li><li>alle societ\u00e0 o soggetti terzi incaricati dei servizi di stampa, imbustamento, spedizione e\/o consegna dei lotti acquistati;<\/li><li>a uffici postali, corrieri o spedizionieri incaricati della consegna dei lotti acquistati;<\/li><li>a societ\u00e0, consulenti o professionisti eventualmente incaricati dell\u2019installazione, della manutenzione, dell\u2019aggiornamento e, in generale, della gestione degli hardware e software di CHAXI, o di cui CHAXI si serve, compreso il Sito;<\/li><li>a societ\u00e0 o Internet provider incaricati dell\u2019invio di documentazione e\/o materiale informativo ovvero pubblicitario; (f) a societ\u00e0 incaricate dell\u2019elaborazione e\/o dell\u2019invio di materiale pubblicitario ed informativo per conto di CHAXI;<\/li><li>a tutti quei soggetti pubblici e\/o privati, persone fisiche e\/o giuridiche (studi di consulenza legale, amministrativa e fiscale, Uffici Giudiziari, Camere di Commercio, Camere ed Uffici del Lavoro, ecc.), qualora la comunicazione risulti necessaria o funzionale al corretto adempimento degli obblighi gravanti su CHAXI.<\/li><li>I Suoi Dati saranno elaborati e diffusi, unicamente in forma anonima ed aggregata, per finalit\u00e0 statistiche o di ricerca.<\/li><\/ul><ul><li><strong>8<\/strong> Titolare del trattamento dei Dati \u00e8 CHAXI GALLERY di Imane Chakhsi, con sede in Via Pietro Cismondi 15 (25030), Roncadelle (BS), al quale \u00e8 possibile rivolgere istanze e richieste relative al trattamento dei Dati scrivendo all\u2019indirizzo email info@chaxigallery.com. L\u2019elenco aggiornato degli eventuali responsabili del trattamento \u00e8 disponibile, su richiesta scritta, presso la sede di CHAXI.<\/li><\/ul><ul><li><strong>9<\/strong> I Dati saranno conservati per un periodo di tempo massimo pari al periodo di prescrizione dei diritti azionabili da CHAXI, come di volta in volta applicabile. Qualora i dati siano trattati per le finalit\u00e0 di marketing e profilazione di cui alle lett. i) ed l), saranno conservati per un periodo di tempo massimo pari, rispettivamente, a 24 e 12 mesi. Le immagini raccolte tramite i sistemi di videosorveglianza sono conservate per un periodo di tempo non superiore alle 24 ore successive alla loro rilevazione, fatte salve particolari esigenze di ulteriore conservazione in relazione a festivit\u00e0 o chiusura delle sedi o nel caso in cui sia necessario aderire ad una specifica richiesta investigativa dell\u2019autorit\u00e0 giudiziaria o della polizia giudiziaria. 17.10 Ai sensi dell\u2019art. 13 e degli artt. 15 e ss. del GDPR, Lei ha diritto, tra l\u2019altro di:<\/li><\/ul><p><strong>(a)<\/strong> ottenere la conferma che sia o meno in corso un trattamento di dati personali che lo riguardano;<\/p><p><strong>(b)<\/strong> qualora un trattamento sia in corso, ottenere l\u2019accesso ai Dati e alle informazioni relative al trattamento, nonch\u00e9 richiedere una copia dei dati personali;<\/p><p><strong>(c)<\/strong> ottenere la rettifica dei Dati inesatti o l\u2019integrazione dei Dati incompleti;<\/p><p><strong>(d)<\/strong> ottenere, qualora sussista una delle condizioni previste dall\u2019art. 17 del GDPR, a cancellazione dei Dati che La riguardano;<\/p><p><strong>(e)<\/strong> ottenere, nei casi previsti dall\u2019art. 18 del GDPR, la limitazione del trattamento;<\/p><p><strong>(f)<\/strong> ricevere, qualora sussistano le condizioni previste dall\u2019art. 20 del GDPR, i Dati che La riguardano in formato strutturato, di uso comune e leggibile da dispositivo automatico e richiedere la loro trasmissione ad un altro titolare del trattamento, se tecnicamente fattibile;<\/p><p><strong>(g)<\/strong> opporsi, in qualsiasi momento, in tutto o in parte, al trattamento dei Dati effettuato per finalit\u00e0 di marketing. L\u2019opposizione al trattamento esercitata attraverso modalit\u00e0 automatizzate di contatto si estende anche all\u2019invio di comunicazioni commerciali a mezzo del servizio postale o di chiamate telefoniche con operatore, fatta salva la possibilit\u00e0 di esercitare tale diritto in parte, opponendosi ad esempio al solo trattamento effettuato mediante sistemi automatizzati di comunicazione;<\/p><p><strong>(h)<\/strong> opporsi, in qualsiasi momento, al trattamento dei Dati effettuato per il perseguimento di un legittimo interesse del Titolare, sempre che non sussistano motivi legittimi per procedere al trattamento che prevalgono sugli interessi, sui diritti e sulle libert\u00e0 dell\u2019interessato oppure per l\u2019accertamento, l\u2019esercizio o la difesa di un diritto in sede giudiziaria;<\/p><p><strong>(i)<\/strong> revocare il consenso in qualsiasi momento, senza pregiudizio alcuno per la liceit\u00e0 del trattamento eseguito in ragione del consenso prestato prima della revoca;<\/p><p><strong>(j)<\/strong> proporre reclamo al Garante per la protezione dei dati personali, secondo le modalit\u00e0 indicate sul sito internet del Garante accessibile all\u2019indirizzo www.garanteprivacy.it.<\/p><p>I diritti di cui sopra potranno essere esercitati con richiesta al Titolare a mezzo posta elettronica al seguente indirizzo: info@chaxigallery.com<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2e63ba38 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2e63ba38\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-385243e4\" data-id=\"385243e4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-477cdb14 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"477cdb14\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Facebook Instagram Twitch Youtube DEFINIZIONI Definizioni Acquirente: la persona fisica o giuridica che in relazione al lotto fa, in asta, l\u2019offerta pi\u00f9 alta accettata dal banditore; Codice del Consumo: il Decreto Legislativo del 6 settembre 2005, n. 2016; Codice Urbani: il Decreto Legislativo del 22 gennaio 2004, n. 42 e sue successive modificazioni o integrazioni. [&hellip;]<\/p>\n","protected":false},"author":26,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1541","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Policy Asta - Chaxi Gallery<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/chaxigallery.com\/it_it\/policy-asta\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Policy Asta - Chaxi Gallery\" \/>\n<meta property=\"og:description\" content=\"Facebook Instagram Twitch Youtube DEFINIZIONI Definizioni Acquirente: la persona fisica o giuridica che in relazione al lotto fa, in asta, l\u2019offerta pi\u00f9 alta accettata dal banditore; Codice del Consumo: il Decreto Legislativo del 6 settembre 2005, n. 2016; Codice Urbani: il Decreto Legislativo del 22 gennaio 2004, n. 42 e sue successive modificazioni o integrazioni. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/chaxigallery.com\/it_it\/policy-asta\/\" \/>\n<meta property=\"og:site_name\" content=\"Chaxi Gallery\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/chaxigallery\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-06T07:21:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/chaxigallery.com\/wp-content\/uploads\/2021\/03\/Logo-grigio-trasoa-768x462.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"50 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/chaxigallery.com\\\/policy-asta\\\/\",\"url\":\"https:\\\/\\\/chaxigallery.com\\\/policy-asta\\\/\",\"name\":\"Policy Asta - Chaxi Gallery\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/chaxigallery.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/chaxigallery.com\\\/policy-asta\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/chaxigallery.com\\\/policy-asta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/chaxigallery.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Logo-grigio-trasoa-768x462.png\",\"datePublished\":\"2022-01-25T11:47:20+00:00\",\"dateModified\":\"2022-02-06T07:21:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/chaxigallery.com\\\/policy-asta\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/chaxigallery.com\\\/policy-asta\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/chaxigallery.com\\\/policy-asta\\\/#primaryimage\",\"url\":\"https:\\\/\\\/chaxigallery.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Logo-grigio-trasoa-768x462.png\",\"contentUrl\":\"https:\\\/\\\/chaxigallery.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Logo-grigio-trasoa-768x462.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/chaxigallery.com\\\/policy-asta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/chaxigallery.com\\\/it_it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Policy Asta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/chaxigallery.com\\\/#website\",\"url\":\"https:\\\/\\\/chaxigallery.com\\\/\",\"name\":\"Galleria d'arte - Chaxi Gallery\",\"description\":\"Galleria d'arte\",\"publisher\":{\"@id\":\"https:\\\/\\\/chaxigallery.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/chaxigallery.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/chaxigallery.com\\\/#organization\",\"name\":\"Chaxi Gallery\",\"url\":\"https:\\\/\\\/chaxigallery.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/chaxigallery.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/chaxigallery.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/cropped-cropped-cropped-Logo-grigio-trasoa.png\",\"contentUrl\":\"https:\\\/\\\/chaxigallery.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/cropped-cropped-cropped-Logo-grigio-trasoa.png\",\"width\":1728,\"height\":474,\"caption\":\"Chaxi Gallery\"},\"image\":{\"@id\":\"https:\\\/\\\/chaxigallery.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/chaxigallery\",\"https:\\\/\\\/www.instagram.com\\\/chaxi_gallery\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@chaxigallery4725\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Policy Asta - Chaxi Gallery","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/chaxigallery.com\/it_it\/policy-asta\/","og_locale":"it_IT","og_type":"article","og_title":"Policy Asta - Chaxi Gallery","og_description":"Facebook Instagram Twitch Youtube DEFINIZIONI Definizioni Acquirente: la persona fisica o giuridica che in relazione al lotto fa, in asta, l\u2019offerta pi\u00f9 alta accettata dal banditore; Codice del Consumo: il Decreto Legislativo del 6 settembre 2005, n. 2016; Codice Urbani: il Decreto Legislativo del 22 gennaio 2004, n. 42 e sue successive modificazioni o integrazioni. [&hellip;]","og_url":"https:\/\/chaxigallery.com\/it_it\/policy-asta\/","og_site_name":"Chaxi Gallery","article_publisher":"https:\/\/www.facebook.com\/chaxigallery","article_modified_time":"2022-02-06T07:21:31+00:00","og_image":[{"url":"https:\/\/chaxigallery.com\/wp-content\/uploads\/2021\/03\/Logo-grigio-trasoa-768x462.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"50 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/chaxigallery.com\/policy-asta\/","url":"https:\/\/chaxigallery.com\/policy-asta\/","name":"Policy Asta - Chaxi Gallery","isPartOf":{"@id":"https:\/\/chaxigallery.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/chaxigallery.com\/policy-asta\/#primaryimage"},"image":{"@id":"https:\/\/chaxigallery.com\/policy-asta\/#primaryimage"},"thumbnailUrl":"https:\/\/chaxigallery.com\/wp-content\/uploads\/2021\/03\/Logo-grigio-trasoa-768x462.png","datePublished":"2022-01-25T11:47:20+00:00","dateModified":"2022-02-06T07:21:31+00:00","breadcrumb":{"@id":"https:\/\/chaxigallery.com\/policy-asta\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/chaxigallery.com\/policy-asta\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/chaxigallery.com\/policy-asta\/#primaryimage","url":"https:\/\/chaxigallery.com\/wp-content\/uploads\/2021\/03\/Logo-grigio-trasoa-768x462.png","contentUrl":"https:\/\/chaxigallery.com\/wp-content\/uploads\/2021\/03\/Logo-grigio-trasoa-768x462.png"},{"@type":"BreadcrumbList","@id":"https:\/\/chaxigallery.com\/policy-asta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/chaxigallery.com\/it_it\/"},{"@type":"ListItem","position":2,"name":"Policy Asta"}]},{"@type":"WebSite","@id":"https:\/\/chaxigallery.com\/#website","url":"https:\/\/chaxigallery.com\/","name":"Galleria d'arte - Chaxi Gallery","description":"Galleria d'arte","publisher":{"@id":"https:\/\/chaxigallery.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/chaxigallery.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/chaxigallery.com\/#organization","name":"Chaxi Gallery","url":"https:\/\/chaxigallery.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/chaxigallery.com\/#\/schema\/logo\/image\/","url":"https:\/\/chaxigallery.com\/wp-content\/uploads\/2021\/12\/cropped-cropped-cropped-Logo-grigio-trasoa.png","contentUrl":"https:\/\/chaxigallery.com\/wp-content\/uploads\/2021\/12\/cropped-cropped-cropped-Logo-grigio-trasoa.png","width":1728,"height":474,"caption":"Chaxi Gallery"},"image":{"@id":"https:\/\/chaxigallery.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/chaxigallery","https:\/\/www.instagram.com\/chaxi_gallery\/","https:\/\/www.youtube.com\/@chaxigallery4725"]}]}},"_links":{"self":[{"href":"https:\/\/chaxigallery.com\/it_it\/wp-json\/wp\/v2\/pages\/1541","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chaxigallery.com\/it_it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/chaxigallery.com\/it_it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/chaxigallery.com\/it_it\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/chaxigallery.com\/it_it\/wp-json\/wp\/v2\/comments?post=1541"}],"version-history":[{"count":7,"href":"https:\/\/chaxigallery.com\/it_it\/wp-json\/wp\/v2\/pages\/1541\/revisions"}],"predecessor-version":[{"id":1715,"href":"https:\/\/chaxigallery.com\/it_it\/wp-json\/wp\/v2\/pages\/1541\/revisions\/1715"}],"wp:attachment":[{"href":"https:\/\/chaxigallery.com\/it_it\/wp-json\/wp\/v2\/media?parent=1541"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}